{"id":98935,"date":"2014-09-09T00:00:00","date_gmt":"2014-09-09T00:00:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=98935"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"LINDA-HESSE-Wissenswertes-uebe-98934","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/pop-schlager\/LINDA-HESSE-Wissenswertes-uebe-98934\/","title":{"rendered":"LINDA HESSE <br \/> Wissenswertes \u00fcber ihre &quot;H\u00f6r auf dein Herz&quot; \u2013 Tournee 2015!"},"content":{"rendered":"<p>&#8222;Lovely Linda&#8220; ist von der Manfred Hertlein Veranstaltungs GmbH zu Semmel Concerts gewechselt!\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">Schon im Fr&uuml;hjahr hat LINDA HESSE mit ihrer Hitsingle &bdquo;KNUTSCHEN&#8230; ich kann nichts daf&uuml;r&ldquo; kribbelige Fr&uuml;hlingsgef&uuml;hle ausgel&ouml;st. (5 Wochen war der Song an der Spitze der konservativen Deutschen Airplay Charts).<\/p>\n<p>Der Sp&auml;tsommer brachte nun ihr lang ersehntes zweites Album &bdquo;H&ouml;r auf dein Herz&ldquo; (V&Ouml; 29.08.2014 ELECTROLA), mit dem sie und ihre Band im Fr&uuml;hjahr 2015 endlich auch wieder auf Tournee gehen werden.<\/p>\n<p>LINDA HESSE, geboren in Halberstadt und inzwischen &uuml;berzeugte Wahlberlinerin, hat in den letzten 18 Monaten f&uuml;r m&auml;chtig Wirbel in der Schlagerszene gesorgt. &bdquo;Neue deutsche Mucke&ldquo;, so bezeichnet die Fachpresse ihren Musikstil. Sie formuliert es einfacher: Musik mit deutschen Texten, ehrlich und handgemacht. Geschichten &ndash; die das Leben schreibt &ndash; mit ganz viel Herz und manchmal auch ein bisschen Verstand.<\/p>\n<p>Mit dieser Mischung wird LINDA HESSE w&auml;hrend ihrer Tournee 14 Konzertst&auml;dte bereisen und ihrem Publikum zeigen, dass ihre &bdquo;neue deutsche Mucke&ldquo; schon&nbsp; jetzt viele Zuh&ouml;rer hat und ihre Fangemeinde w&ouml;chentlich w&auml;chst und w&auml;chst und w&auml;chst&#8230;. LINDA HESSE versteht es, Musikelemente zu mischen und Texte, deren Poesie zum Tr&auml;umen einl&auml;dt, mit einer Prise Humor des eigenwilligen Stils einer LINDA HESSE zu versehen. Ein Stil der neuartig ist und irgendwo zwischen frechem, frischem Schlager und Deutsch-Pop zu finden ist. Der Titel aus ihrem aktuellen Album &quot;Knutschen &ndash; ich kann nichts daf&uuml;r&quot; hat bereits jetzt einen regelrechten &quot;Knutschalarm&quot; bei vielen Radiostationen ausgel&ouml;st. Ein Titel bei dem LINDA HESSE das genannte &bdquo;Hesse&acute;sche&ldquo; Gesp&uuml;r f&uuml;r deutsche Texte und die perfekte Stilmischung bewiesen hat.<\/p>\n<p>LINDA Hesse pr&auml;sentiert auf ihrer Tournee Titel aus dem aktuellen Album, aber auch bereits bekannte Songs. So zum Beispiel &quot;Punktgenaue Landung&quot; ihr &quot;Erstling&quot;, wie Linda Hesse ihren ersten Erfolg liebevoll getauft hat. &Uuml;berhaupt darf man auf die Konzerte der 27j&auml;hrigen Musikerin gespannt sein. Ihre Titel klingen mal nachdenklich, mal vertr&auml;umt, mal erfrischend, witzig, frech &ndash; eine Mischung, die ihr Publikum und ihre Fangemeinde endlich im Fr&uuml;hjahr live erleben d&uuml;rfen.<\/p>\n<p style=\"text-align: justify;\">\n<p>Jetzt <strong><a href=\"http:\/\/www.semmel.de\/linda-hesse-hoer-auf-dein-herz-tournee-2015.html\">HIER<\/a><\/strong> Tickets f&uuml;r eines ihrer 14 Konzerte sichern!<\/p>\n<p><em>Foto-Credit: Electrola \/ Thommy S. Mardo <\/em><\/p>\n<p>Meine Musik &#8211; Das Liveportal (Textvorlage)<br \/>http:\/\/www.universal-music.de\/company\/umg\/electrola<br \/>http:\/\/linda-hesse.de\/index.php<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8222;Lovely Linda&#8220; ist von der Manfred Hertlein Veranstaltungs GmbH zu Semmel Concerts gewechselt!\u00a0 Schon im Fr&uuml;hjahr hat LINDA HESSE mit<\/p>\n","protected":false},"author":2,"featured_media":98936,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[28],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/98935"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=98935"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/98935\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/98936"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=98935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=98935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=98935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}