{"id":96412,"date":"2014-11-17T00:00:00","date_gmt":"2014-11-17T00:00:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=96412"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"ANDREAS-OSCAR-Sein-aktueller-Ti-96411","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/country\/ANDREAS-OSCAR-Sein-aktueller-Ti-96411\/","title":{"rendered":"ANDREAS OSCAR <br \/>Sein aktueller Titel hei\u00dft &quot;Alles vergeht &#8211; nur eins bleibt&quot;!"},"content":{"rendered":"<p>F\u00fcr Andreas Oscar bleibt immer die Liebe&#8230;:\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">ANDREAS OSCAR z&auml;hlt seit einigen Jahren zu den beliebtesten Countrys&auml;ngern des Landes. Das beweisen nicht zuletzt seine Nominierungen und Auszeichnungen bei den jeweiligen Awards. Nach Erscheinen seines Albums <strong>&bdquo;An deiner Seite&ldquo;<\/strong> (A1\/A2-Records) nahm er weitere Titel auf. <strong>&quot;Haus an Haus<\/strong>&quot; aus 2014 (A la tete Records) schaffte es bis auf Platz 23 der &quot;Offiziellen deutschen Party und Schlager-Charts. Nun pr&auml;sentiert er auf diesem Label mit <strong>&quot;Alles vergeht &#8211; nur eins bleibt<\/strong>&quot; eine gef&uuml;hlvolle Ballade.&nbsp;&nbsp;Dabei mischt der geb&uuml;rtige Sachse &nbsp;klassische Country-Kl&auml;nge mit modernen und popul&auml;ren Musikelementen, dr&uuml;ckt in seinen Texten gern gro&szlig;e Gef&uuml;hle aus.<\/p>\n<p>Bis zu seiner Ausreise 1988 hatte Andreas mit Ehefrau Conny und T&ouml;chterchen im s&auml;chsischen Niesky bei G&ouml;rlitz gewohnt, wo er auch seine Schulzeit verbrachte. Dort geh&ouml;rte er zum Schulchor, lernte Tenorhorn und bekam eine klassische Gesangausbildung. Irgendwann fiel ihm eine Gitarre in die H&auml;nde, die er am liebsten gar nicht mehr losgelassen h&auml;tte. Er nahm daraufhin Unterricht an den Saiten. Es und einige Jahre als S&auml;nger in einer Coverband.<\/p>\n<p>Nach der Wende lie&szlig; er sich in der N&auml;he von N&uuml;rnberg nieder, arbeitete in der Konstruktionsabteilung einer mittelgro&szlig;en Stahlfirma und wohnt nun in der f&uuml;nftgr&ouml;&szlig;ten Stadt des Freistaates Bayern &#8211; in Ansbach. Dort war nicht nur das ber&uuml;hmte Findelkind Kaspar Hauser wohnhaft, auch der Astronom Simon Marius, der noch vor Galileo Galilei die Monde des Jupiter von den T&uuml;rmen des dortigen Schlosses entdeckt haben soll.<\/p>\n<p>Zu den Sternen m&ouml;chte auch Andreas gelangen, allerdings mehr mit Stimme und Songs. Der geb&uuml;rtige Sachse wurde inzwischen mehrfach nominiert f&uuml;r den Deutschen Countrypreis, errang den Schlager Rallye Ehren-Award. Bekannt wurde er durch Hitparadenplatzierungen mit &bdquo;Engel, Teufel, Lady und Sphinx&ldquo;, &bdquo;Die Nadel im Heu&ldquo; oder &bdquo;Jahreszeiten&ldquo;, erreichte Platz 1 in verschiedenen ARD-Hitparaden.<\/p>\n<p>Alibaba-Musikproduktion, Klaus Pelizaeus (Textvorlage)<br \/>http:\/\/www.alatete.de<br \/>http:\/\/www.vcdi.de\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr Andreas Oscar bleibt immer die Liebe&#8230;:\u00a0 ANDREAS OSCAR z&auml;hlt seit einigen Jahren zu den beliebtesten Countrys&auml;ngern des Landes. Das<\/p>\n","protected":false},"author":2,"featured_media":96413,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[4],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/96412"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=96412"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/96412\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/96413"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=96412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=96412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=96412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}