{"id":94744,"date":"2015-01-08T07:51:00","date_gmt":"2015-01-08T07:51:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=94744"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"KRISTINA-BACH-Die-Hit-Autorin-d-94743","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/schlager\/KRISTINA-BACH-Die-Hit-Autorin-d-94743\/","title":{"rendered":"KRISTINA BACH <br \/>Die &quot;Hit-Autorin des Jahres (&#39;Atemlos durch die Nacht&#39;)&quot; in der ARD-Show &quot;Das gro\u00dfe Fest der Besten&quot; zu Gast!"},"content":{"rendered":"<p>Florian Silbereisen pr\u00e4sentiert die Stars des Jahres! \u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">KRISTINA BACH (- &quot;Die deutsche Dianne Warren&quot;; <em>smago! <\/em>-) ist am Samstag (10.01.2015) in der ARD-Show &quot;Das gro&szlig;e Fest der Besten &#8211; Florian Silbereisen pr&auml;sentiert die Stars des Jahres&quot; zu Gast.<\/p>\n<p>Kristina Bach hat den Superhit &quot;Atemlos durch die Nacht&quot; f&uuml;r Helene Fischer geschrieben und diesen selbst in englischer Sprache (&quot;Take A Breath&quot;) eingesungen.<\/p>\n<p>&quot;Atemlos durch die Nacht&quot; ist mittlerweile nicht nur hochoffiziell der &quot;Hit des Jahres 2014&quot; \/\/ die meistverkaufte Single des Jahres in Deutschland &uuml;berhaupt, sondern &#8211; nach dem Daf&uuml;rhalten von smago! &#8211; der erfolgreichste genre&uuml;bergreifender Schlager aller Zeiten!<\/p>\n<p>Eine Leistung, die es uneingeschr&auml;nkt anzuerkennen gilt!<\/p>\n<p>Leider konnte Kristina Bach den ihr zugedachten <em>smago!<\/em> Award am 26.11.2014 im &quot;MOA&quot; Berlin nicht entgegennehmen, da sie kurzzeitig akut erkrankt war.<\/p>\n<p>Andy Tichler, Chefredakteur www.smago.de<\/p>\n<p>http:\/\/www.kristina-bach.de\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Florian Silbereisen pr\u00e4sentiert die Stars des Jahres! \u00a0 KRISTINA BACH (- &quot;Die deutsche Dianne Warren&quot;; smago! -) ist am Samstag<\/p>\n","protected":false},"author":2,"featured_media":94745,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[29],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/94744"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=94744"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/94744\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/94745"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=94744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=94744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=94744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}