{"id":92992,"date":"2015-02-27T00:37:00","date_gmt":"2015-02-27T00:37:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=92992"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"ANDREA-BERG-Traeumer-wie-wir-92991","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/schlager\/ANDREA-BERG-Traeumer-wie-wir-92991\/","title":{"rendered":"ANDREA BERG <br \/>&quot;Tr\u00e4umer wie wir&quot; &#8211; Die aktuelle Radio-Single von Andrea Berg!"},"content":{"rendered":"<p>Musik: Dieter Bohlen; Text: Andrea Berg!\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">Mit &bdquo;Atlantis&ldquo; hat sich ANDREA BERG einen Herzenswunsch erf&uuml;llt. Nicht nur, dass die geb&uuml;rtige Krefelderin ihre eigene Traumwelt erschuf und f&uuml;r die Titelbilder sogar selbst in die Tiefen des Wassers eintauchen durfte. Mit dem mittlerweile 5-fach goldpr&auml;mierten Doppelalbum hat Deutschlands erfolgreichste K&uuml;nstlerin die Herzen ihrer Fans getroffen. Folgerichtig erscheint nun mit &bdquo;Tr&auml;umer wie wir&ldquo; aus der Feder von Dieter Bohlen die f&uuml;nfte Single-Auskopplung. Und wie die vier Vorg&auml;nger hat auch &bdquo;Tr&auml;umer wie wir&ldquo; absolutes, wenn nicht schon garantiertes Hitpotential.<\/p>\n<p>W&auml;hrend der im Jahr 2014 stattfindenden Atlantis-Tour entwickelte sich der Up-Tempo-Song zu einem wahren Publikumsliebling. Und auch bei den anstehenden Open Air-Konzerten inklusive dem zehnten Kult-Open Air &bdquo;Heimspiel&ldquo; in Aspach wird die Nummer wieder f&uuml;r ganz besondere Momente sorgen.<\/p>\n<p>Die neue Single &bdquo;Tr&auml;umer wie wir&ldquo; wurde zum heutigen Freitag (27.02.2015) an die Radiostationen bemustert.<\/p>\n<p>Ariola (Textvorlage)<br \/>http:\/\/www.ariola.de<br \/>http:\/\/www.andrea-berg.de\/home<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Musik: Dieter Bohlen; Text: Andrea Berg!\u00a0 Mit &bdquo;Atlantis&ldquo; hat sich ANDREA BERG einen Herzenswunsch erf&uuml;llt. Nicht nur, dass die geb&uuml;rtige<\/p>\n","protected":false},"author":2,"featured_media":92993,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[29],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/92992"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=92992"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/92992\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/92993"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=92992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=92992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=92992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}