{"id":87574,"date":"2015-07-31T16:35:00","date_gmt":"2015-07-31T16:35:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=87574"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"ROLAND-KAISER-In-grosser-Vorfre-87573","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/schlager\/ROLAND-KAISER-In-grosser-Vorfre-87573\/","title":{"rendered":"ROLAND KAISER <br \/>In gro\u00dfer Vorfreude auf seine vier &quot;Kaisermania&quot; Konzerte!"},"content":{"rendered":"<p>Einen kleinen Vorgeschmack gibt\u00b4s heute Vorabend um 17:15 Uhr in der Sendung &#8222;Brisant&#8220; (Das Erste \/ ARD)! Und: Die (ersten) Termine f\u00fcr die &#8222;Kaisermania 2016&#8220; stehen&#8230;:\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\"><em>Liebe Freunde,<\/em><br \/>\n&nbsp;<\/p>\n<p style=\"text-align: justify;\"><em>heute ist der gro&szlig;e Tag: Die zw&ouml;lfte Kaisermania beginnt um 20:00 Uhr. Die beiden kommenden Wochenenden werden f&uuml;r mich ganz sicher ein absolutes Highlight in diesem Jahr, wie f&uuml;r Euch hoffentlich auch.<\/p>\n<p>Wie sch&ouml;n ist es, schon jetzt zu wissen, dass ich und meine Band auch im n&auml;chsten Jahr wieder zur&uuml;ck an das Elbufer kommen werden: die Termine f&uuml;r die Kaisermania 2016 sind der 29. und 30.07.2016; der Vorverkauf startet in K&uuml;rze.<\/p>\n<p>Wir sehen uns!<\/em><\/p>\n<p>&nbsp;<\/p>\n<div class=\"text_exposed_show\">\n<p style=\"text-align: justify;\"><em>Euer Roland<\/em><br \/>\n&nbsp;<\/p>\n<p style=\"text-align: justify;\"><em>P.S.: Einen kleinen Vorgeschmackt auf heute Abend k&ouml;nnt Ihr um 17:15 in der ARD Sendung Brisant erleben.<\/em><\/p>\n<\/div>\n<p>Andy Tichler, Chefredakteur www.smago.de<br \/>http:\/\/www.ariola.de<br \/>http:\/\/www.roland-kaiser.de<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Einen kleinen Vorgeschmack gibt\u00b4s heute Vorabend um 17:15 Uhr in der Sendung &#8222;Brisant&#8220; (Das Erste \/ ARD)! Und: Die (ersten)<\/p>\n","protected":false},"author":2,"featured_media":87575,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[29],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/87574"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=87574"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/87574\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/87575"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=87574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=87574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=87574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}