{"id":85027,"date":"2015-10-02T00:08:00","date_gmt":"2015-10-02T00:08:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=85027"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"BRUNNER-amp-STELZER-vormals-Simone-amp-C-85026","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/schlager\/BRUNNER-amp-STELZER-vormals-Simone-amp-C-85026\/","title":{"rendered":"BRUNNER &#038; STELZER ((vormals: Simone &#038; Charly Brunner)) <br \/>Sie laden alle auf ihre &quot;Arche Noah&quot; ein!"},"content":{"rendered":"<p>Das zweite Duett-Album &#8222;Alles geht!&#8220; erscheint am 27. November 2015!\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">Das zweite gemeinsame Album von Charly Brunner und Simone Stelzer k&uuml;ndigt sich an: Bevor &bdquo;Alles geht!&ldquo; am 27.11.2015 erscheint, wird die erste Single daraus ver&ouml;ffentlicht: &bdquo;Arche Noah&ldquo;.<\/p>\n<p>Man merkt es sofort: Aus dem Projekt &bdquo;&acute;&acute;Simone &amp; Charly Brunner&ldquo; ist eine enge Zusammenarbeit zweier K&uuml;nstler entstanden, die sich auf Augenh&ouml;he begegnen und sich wunderbar und harmonisch erg&auml;nzen.<\/p>\n<p style=\"text-align: justify;\">&bdquo;Vielleicht reibt sich der eine oder andere jetzt die Augen, wenn er BRUNNER &amp; STELZER liest&ldquo;, erz&auml;hlt Charly, &bdquo;doch auch daran wird man sich gew&ouml;hnen&ldquo;, wirft Simone lachend ein. Und Charly erg&auml;nzt: &bdquo;Wir waren mit &bdquo;Simone und Charly Brunner&ldquo; nie so wirklich gl&uuml;cklich und als wir dann am Ende der Produktion unseres neuen Albums die Lieder einzeln und gemeinsam mit unserem Produzenten Matze Roska durchgeh&ouml;rt hatten, sagte er spontan: Das war das neue Album von BRUNNER &amp; STELZER. Das hatte Kraft, wir sahen uns alle an und die Marke war geboren.&ldquo;<\/p>\n<p style=\"text-align: justify;\">Die neue Single-Auskoppelung &bdquo;Arche Noah&ldquo; ist ein positives St&uuml;ck Schlager-Pop. Die Idee f&uuml;r diesen Song hatte Simone schon vor fast einem Jahr.<\/p>\n<p>&bdquo;Jeder von uns, auch wenn wir es oft nicht zugeben wollen, braucht irgendwann jemanden. Jemanden ,der zuh&ouml;rt, wenn wir reden wollen, jemanden, der uns in die Arme nimmt, wenn wir nach Geborgenheit suchen. Jeder kann f&uuml;r jeden eine &bdquo;Arche&ldquo; sein!<\/p>\n<p>Das ist die Essenz der neuen Single &bdquo;Arche Noah&ldquo;, gepackt in eine Melodie, die einem nicht mehr aus den Ohren geht.<\/p>\n<p>Der Einstieg in &bdquo;Alles geht!&ldquo; ist also gelungen und die Fans von Charly Brunner &amp; Simone Stelzer werden sich freuen, wenn sie es am 27.11.2015 auch endlich h&ouml;ren k&ouml;nnen.<\/p>\n<p>Passend zur Ver&ouml;ffentlichung des neuen Albums werden BRUNNER &amp; STELZER &uuml;brigens ab 26. November 2015 an der gro&szlig;en Tour der &bdquo;Weihnachts-Gala der Deutschen Fernsehlotterie&ldquo; teilnehmen, die die beiden bis zum 19.12.2105 durch zehn St&auml;dte f&uuml;hren wird. 2016 sind sie auch mit Stefan Mross und seiner &bdquo;Immer wieder sonntags- Unterwegs&ldquo;-Tour bei allen Terminen dabei.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Weitere Infos unter: <strong><a href=\"http:\/\/www.simone.at\">www.simone.at<\/a><\/strong>, <strong><a href=\"http:\/\/www.charly-brunner.com\">www.charly-brunner.com<\/a><\/strong> und in absehbarer Zeit <strong><a href=\"http:\/\/www.brunner-stelzer.at\">www.brunner-stelzer.at<\/a><\/strong>!<\/p>\n<p>Ariola (Textvorlage)<br \/>http:\/\/www.ariola.de<br \/>http:\/\/www.brunner-stelzer.at<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das zweite Duett-Album &#8222;Alles geht!&#8220; erscheint am 27. November 2015!\u00a0 Das zweite gemeinsame Album von Charly Brunner und Simone Stelzer<\/p>\n","protected":false},"author":2,"featured_media":85028,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[29],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/85027"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=85027"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/85027\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/85028"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=85027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=85027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=85027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}