{"id":84889,"date":"2015-10-09T00:00:00","date_gmt":"2015-10-09T00:00:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=84889"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"VICKY-LEANDROS-Ich-weiss-dass-i-84888","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/schlager\/VICKY-LEANDROS-Ich-weiss-dass-i-84888\/","title":{"rendered":"VICKY LEANDROS <br \/>&quot;Ich wei\u00df, dass ich nichts wei\u00df&quot; ODER Vicky&#39;s K\u00fcchenlieder!"},"content":{"rendered":"<p>Wie wir auf diese Schnapsidee kommen, die 12 hervorragenden Songs als &#8222;K\u00fcchenlieder&#8220; bzw. als &#8222;Lieder aus der K\u00fcche&#8220; zu bezeichnen &#8230;:\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">VICKY LEANDROS steckt voller Tatendrang. Mit ihrem neuen Studioalbum &#39;Ich wei&szlig;, dass ich nichts wei&szlig;&#39;, dem ersten seit f&uuml;nf Jahren, hat die deutsch-griechische Gesangslegende nun ihr pers&ouml;nlichstes Werk in ihrer spektakul&auml;ren Karriere aufgenommen. Die meisten Songs des neuen Albums hat Vicky Leandros selbst komponiert und getextet. Hier und da hat sie mit anderen Autoren an den Texten gefeilt, zwei Songs stammen von Peter Plate (Rosenstolz, Sarah Connor) und seinem Team, mit dem sie befreundet ist.<\/p>\n<p>Eine Besonderheit dieses neuen Albums ist, dass die meisten Gesangsaufnahmen in der K&uuml;che im Haus von Vicky Leandros mit einem mobilen Recording-Equipment mitgeschnitten wurden. In dieser behaglichen Atmosph&auml;re, in der sie auch stets ihre G&auml;ste vorz&uuml;glich zu bekochen und zu bewirten wei&szlig;, f&uuml;hlt sich die K&uuml;nstlerin besonders wohl. Mit den 12 neuen Songs ist Vicky Leandros ein rundum ausgewogen produziertes Album gelungen, das einerseits das Leben mit Augenzwinkern betrachtet, sich andererseits nicht scheut, viel Gef&uuml;hl zu zeigen. Vicky Leandros abschlie&szlig;end &uuml;ber ihr neues Werk: &#39;Es ist das pers&ouml;nlichste Studioalbum, das ich je auf genommen habe!&#39;<\/p>\n<p>Neben der Standard Version im Jewelcase, erscheint das Album zudem in einer limitierten Premium Edition im Digipak inkl. diversen neuen Songs in grandios arrangierten Akustikversionen.<\/p>\n<p><em>Foto-Credit: Walter Kober<\/em><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p><iframe loading=\"lazy\" allowfullscreen=\"\" frameborder=\"0\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/qcIIxdGT2s0\" width=\"560\"><\/iframe><\/p>\n<p>Ariola (Textvorlage)<br \/>http:\/\/www.ariola.de<br \/>http:\/\/www.vickyleandros.eu\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie wir auf diese Schnapsidee kommen, die 12 hervorragenden Songs als &#8222;K\u00fcchenlieder&#8220; bzw. als &#8222;Lieder aus der K\u00fcche&#8220; zu bezeichnen<\/p>\n","protected":false},"author":2,"featured_media":84890,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[29],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/84889"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=84889"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/84889\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/84890"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=84889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=84889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=84889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}