{"id":84886,"date":"2015-10-07T00:00:00","date_gmt":"2015-10-07T00:00:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=84886"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"CELTIC-WOMAN-feat-OONAGH-Bezueg-84885","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/pop\/CELTIC-WOMAN-feat-OONAGH-Bezueg-84885\/","title":{"rendered":"CELTIC WOMAN feat. OONAGH <br \/>Bez\u00fcglich des Titels &quot;T\u00edr na n\u00d3g&quot; machen sie gemeinsame Sache!"},"content":{"rendered":"<p>Senta-Sofia Delliponti &#8211; alias Oonagh &#8211; zeigt sich begeistert von der Zusammenarbeit mit den charmanten Irinnen &#8230;: \u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">P&uuml;nktlich zum 10-j&auml;hrigen Bestehen wartet das weltweit gefeierte irische Damen-Quartett <strong>Celtic Woman <\/strong>mit neuem Album und einer echten &Uuml;berraschung f&uuml;r das deutsche Publikum auf: F&uuml;r die Single <strong>&quot;Tir Na Nog&quot; <\/strong>konnte die deutsche S&auml;ngerin <strong>Oonagh<\/strong>, deren Deb&uuml;t-Album bereits Platinstatus erreichte, f&uuml;r eine Zusammenarbeit gewonnen werden. Senta-Sofia Delliponti, alias <strong>Oonagh<\/strong>, zeigte sich begeistert von der Zusammenarbeit mit den charmanten Irinnen: <em>&quot;Von einem weltweit erfolgreichen Act wie den Celtic Woman zu einem Duett eingeladen zu werden freut mich nicht nur, sondern ehrt mich zutiefst.&quot;<\/em> <strong>&quot;Tir Na Nog&quot; <\/strong>vereint die einzigartigen keltischen Harmonien der <strong>Celtic Woman <\/strong>mit der pr&auml;gnanten Stimme von <strong>Oonagh<\/strong>, die gemeinsam die faszinierenden Bilder von fernen L&auml;ndern und mystischen Orten beschw&ouml;ren. Der vom preisgekr&ouml;nten &quot;Elephant Music Team&quot; geschriebene Song besticht durch seinen mitrei&szlig;enden Rhythmus und die Kombination aus keltischem Flair und traditionellen Stammesrhythmen.<\/p>\n<p>Am 23.10.2015 wird das Jubil&auml;umsalbum <strong>&quot;Destiny&quot; <\/strong>von <strong>Celtic Woman <\/strong>ver&ouml;ffentlicht, ein Album auf dem einzigartige keltische Harmonien von M&aacute;ir&eacute;ad Nesbitt (Violine) und den S&auml;ngerinnen Mair&eacute;ad Carlin, Susan McFadden und &Eacute;abha McMahon mit der pr&auml;gnanten Stimme von <strong>Oonagh <\/strong>vereint werden.Mehrfach Platin in den USA und Gold in Deutschland z&auml;hlen bereits zu den Erfolgen von <strong>Celtic Woman<\/strong>. Nun wird <strong>&quot;Destiny&quot; <\/strong>auf dem deutschen Markt weltweit als erstes verf&uuml;gbar sein. <em>&quot;Viele Songs auf <\/em><strong><em>&quot;Destiny&quot;<\/em><\/strong><em> wurden im Interesse unserer deutschen Fans ausgew&auml;hlt und wir freuen uns besonders, mit unserer Musik und unserem einzigartigen Sound ein noch breiteres Publikum erreichen zu k&ouml;nnen&quot;<\/em> verk&uuml;ndet <strong>Celtic Woman <\/strong>Mitglied Mair&eacute;d Carlin.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>1. &quot;T&iacute;r na n&Oacute;g&quot; &#8211; 3:07<\/strong><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">(Written by Hannes Braun Written by Hartmut Krech Written by Mark Nissen Written by Lukas Hainer Published By: Sony\/ATV\/EMI gmbH)<\/p>\n<p style=\"text-align: justify;\"><strong>Produced by Hannes Braun Produced by Hartmut Krech Produced by Mark Nissen<\/strong><\/p>\n<p style=\"text-align: justify;\">(P) 2015 Celtic Woman Ltd., Under Exclusive License To Manhattan Records<\/p>\n<p style=\"text-align: justify;\">(C) 2015 Deutsche Grammophon GmbH, Berlin<\/p>\n<p>Panorama \/ Deutsche Grammophon GmbH, Berlin (Textvorlage)<br \/>http:\/\/www.universal-music.de\/company\/umg\/electrola<br \/>http:\/\/www.oonagh.tv\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Senta-Sofia Delliponti &#8211; alias Oonagh &#8211; zeigt sich begeistert von der Zusammenarbeit mit den charmanten Irinnen &#8230;: \u00a0 P&uuml;nktlich zum<\/p>\n","protected":false},"author":2,"featured_media":84887,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[27],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/84886"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=84886"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/84886\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/84887"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=84886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=84886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=84886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}