{"id":84829,"date":"2015-10-08T00:00:00","date_gmt":"2015-10-08T00:00:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=84829"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"AMIGOS-Amigos-Konzert-in-Erfurt-84828","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/schlager\/AMIGOS-Amigos-Konzert-in-Erfurt-84828\/","title":{"rendered":"AMIGOS <br \/>Amigos-Konzert in Erfurt verschoben: Th\u00fcringenhalle zur Notunterkunft f\u00fcr Fl\u00fcchtlinge umfunktioniert!"},"content":{"rendered":"<p>Pikant: Die Veranstalter bekommen keinerlei Kosten erstattet !!!\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">Aufgrund der Fl&uuml;chtlingssituation sind derzeit alleine in Erfurt zwei Hallen unbespielbar: zum einen die Th&uuml;ringenhalle, zum anderen die Trainingshalle S&uuml;d hinter der Schwimmhalle. Nachdem die Fl&uuml;chtlinge vom Gel&auml;nde der Messe Erfurt umquartiert werden mussten, wurden beide Hallen zu Notunterk&uuml;nften umfunktioniert.<\/p>\n<p style=\"text-align: justify;\">Das bedeutet, dass einige geplante Veranstaltungen verschoben oder sogar abgesagt werden m&uuml;ssen. Pikant: Die Politik l&auml;sst die Veranstalter auf ihren Kosten sitzen!<\/p>\n<p>Auch die AMIGOS sowie deren &ouml;rtliche(r) Veranstalter sind von der Situation betroffen. Im Falle der Amigos konnte jedoch eine L&ouml;sung gefunden werden: Bernd und Karl-Heinz Ulrich weichen auf die Messehalle Erfurt aus und holen ihr Erfurt-Konzert am 06.12.2015 nach.<\/p>\n<p style=\"text-align: justify;\">Was aus dem f&uuml;r den 24.10.2015 geplanten &quot;Fantasy &#8211; Live&quot; Konzert in Erfurt wird, stand zumindest am Montag (05.10.2015) noch in den Sternen &#8230;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p><iframe loading=\"lazy\" allowfullscreen=\"\" frameborder=\"0\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/C2cMG33mWVY\" width=\"420\"><\/iframe><\/p>\n<p>Andy Tichler, Chefredakteur www.smago.de<br \/>http:\/\/www.ariola.de<br \/>http:\/\/www.die-amigos.de<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pikant: Die Veranstalter bekommen keinerlei Kosten erstattet !!!\u00a0 Aufgrund der Fl&uuml;chtlingssituation sind derzeit alleine in Erfurt zwei Hallen unbespielbar: zum<\/p>\n","protected":false},"author":2,"featured_media":84830,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[29],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/84829"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=84829"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/84829\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/84830"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=84829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=84829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=84829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}