{"id":67330,"date":"2017-04-07T00:00:00","date_gmt":"2017-04-07T00:00:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=67330"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"ANDY-BORG-Die-neue-CD-Cara-mia-67329","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/schlager\/ANDY-BORG-Die-neue-CD-Cara-mia-67329\/","title":{"rendered":"ANDY BORG <br \/>Die neue CD &quot;Cara mia&quot; &#8211; besprochen von Stephan Imming!"},"content":{"rendered":"<p>Passend zum humorvollen Interpreten hat der smago! Kolumnist augenzwinkernde Zeilen zur neuen CD des beliebten S\u00e4ngers geschrieben &#8230;:\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">Mit Meeresrauschen f&auml;ngt sie an, die erste Nummer der aktuellen Andy Borg-CD. Sie klingt nach traditionellem Schlager &ndash; die &Auml;hnlichkeiten der Strophen seines eigenen Klassikers &bdquo;Die Fischer von San Juan&ldquo; mit dem aktuellen Titellied &bdquo;<strong>Cara Mia<\/strong>&ldquo; (bitte nicht mit &bdquo;Karabiner&ldquo; verwechseln!) sind deutlich h&ouml;rbar. Textprobe gef&auml;llig? Borg: &nbsp;&bdquo;<em>Die Augen so tief wie der See<\/em>&ldquo; &ndash; Backgroundcchor: &bdquo;<em>der See, der See<\/em>&ldquo;&hellip; &#8211; Andy Borg &bdquo;<em>ruft in die Ferne und fragt die Sterne und sucht jede Nacht nach ihr<\/em>&ldquo;. Vielleicht ist Cara Mia ja die Frau aus Mendocino, die Michael Holm einst gesucht hatte? Bereits im Oktober 2016 stellte Borg den Song jedenfalls in Carmen Nebels Show vor.<\/p>\n<p>Der Schmuseschlager &bdquo;<strong>Wenn Du einsam bist<\/strong>&ldquo;, geschrieben vom Calimeros-Chef Roland Eberhart, war eigentlich als neue Singleauskopplung gedacht &ndash; wie <em>smago!<\/em> berichtet hat, hat man sich nun aber f&uuml;r den Titel &bdquo;Sarah&ldquo; entschieden, weil Andy den in der von Florian Silbereisen moderierten TV-Show &bdquo;Schlagercountdown&ldquo; zu Geh&ouml;r gebracht hat.<\/p>\n<p>Nach Namen wie &bdquo;Claire&ldquo; und &bdquo;Christine&ldquo; hat Andy nun den besagten neuen Schwarm:&nbsp; &bdquo;<em>Saaaaaaaraaaaah &ndash; Du musst der Sommer sein<\/em>&ldquo; &ndash; ein eing&auml;ngiger neuer Borg-Titel. Das ist f&uuml;rwahr ein toller eing&auml;ngiger melodi&ouml;ser Titel, bei dem man sofort mitsingen kann: &bdquo;<strong><em>Sarah<\/em><\/strong><em> &ndash; so s&uuml;&szlig; wie Sommerwein &ndash; Sarah, sei heut Nacht mein!<\/em>&ldquo;. Das klingt doch nun wirklich romantischer als &bdquo;Geh mal Bier holen, Du wirst schon wieder h&auml;sslich&ldquo; &ndash; nein, Spa&szlig; beiseite, das ist wirklich ein Old-School-Schlager, der Spa&szlig; macht.. Co-Autor des Songs ist &uuml;brigens Oliver Lucas, der mit Dieter Bohlen zusammenarbeitet. U. a. schrieb er Texte f&uuml;r die Erfolgs-CD &bdquo;Freudenspr&uuml;nge&ldquo; von Fantasy und den Beatrice-Egli-Hit &bdquo;Mein Herz&ldquo;.<\/p>\n<p>Sehr pathetisch und romantisch besingt Andy die von seinem langj&auml;hrigen Kumpel Mel Jersey getextete Ballade &nbsp;&bdquo;<strong>Sommertraum<\/strong>&ldquo;, in der er seine mehr als bemerkenswerte Stimme erneut zeigen kann &ndash; sogar ein kleines gewagtes Gitarrensolo erfreut den geneigten Fan. Komponiert wurde der Titel &uuml;brigens von Dries Holten, der als &bdquo;Andres&ldquo; vom Duo &bdquo;Sandra &amp; Andres&ldquo; und Songautor des Klassikers &bdquo;Immer wieder sonntags&ldquo; bekannt wurde. Mel Jersey hat den &bdquo;Sommertraum&ldquo; 1988 selber auch als Single ver&ouml;ffentlicht.<\/p>\n<p>Im Schlager &bdquo;<strong>Himmelsm&auml;rchen<\/strong>&ldquo; will Borg &bdquo;in die Naaaacht hinein tanzen&ldquo; &ndash; Andy pr&auml;sentiert wieder alle Vorz&uuml;ge seiner Stimme in dieser Komposition, die das Team um G. G. Anderson beigesteuert hat (neben Gerd Grabowski schrieben Norbert Hammerschmidt und Engelbert Simons den Schlager).<\/p>\n<p>A propos &bdquo;Tanzen&ldquo; &ndash; darum geht es auch im n&auml;chsten Schlager: &bdquo;<em>Tanz mit mir, Corinna war dein Lieblingslied<\/em>&ldquo; &ndash; anscheinend war der Titel Inspiration f&uuml;r den Song &bdquo;<strong>Komm, wir tanzen<\/strong> unser Lieblingslied&ldquo; &ndash; ein interessanter Gedanke f&uuml;r einen Tanzanalphabeten wie mich. Man kann also Lieder tanzen? Das kannte ich bislang nur aus der Waldorfschule, wobei da meines Wissens nur Namen und nicht Lieder getanzt werden. Andy Borg &ouml;ffnet halt Horizonte&hellip; auch, wenn man sich von der Melodie etwas an &bdquo;Arrivederci Claire&ldquo; erinnert f&uuml;hlt. Den Schlager hat Borg h&ouml;chstselbst f&uuml;r sich geschrieben.<\/p>\n<p>Wer erinnert sich nicht an Andys Hit &bdquo;Angelo mio&ldquo;? Das Thema &bdquo;Angelo&ldquo; l&auml;sst ihn nicht los: &bdquo;<strong>Schick mir einen Engel her &ndash; un angelo per me!<\/strong>&ldquo;. Die Fortf&uuml;hrung dieses Reims ist mehr als bemerkenswert: <em>&bdquo;&hellip;einen, der die Sehnsucht kennt &ndash; lass ihn in meiner N&auml;h&rsquo;<\/em>&ldquo;.. &ndash; wow, das ist wirklich mal kreativ&hellip; &bdquo;lass ihn in meiner(!) N&auml;h&ldquo; &ndash; dem kann ich intellektuell leider nur bedingt folgen&hellip; Wobei auch der Titel eing&auml;ngig ist und als Ohrwurm durchgeht. Die Geschichte des Schlagers ist &uuml;brigens spannend: Der S&auml;nger Omar beteiligte sich damit bereits 2005 an der S&uuml;dtiroler Vorentscheidung zum Grand Prix der Volksmusik. Vier Jahre sp&auml;ter nahm Udo Wenders den Titel mit auf sein Album &bdquo;Z&auml;rtliche Signale&ldquo;, das &uuml;brigens von Christian Zierhofer produziert wurde, der auch f&uuml;r die Produktion dieses neuen Borg-Albums zust&auml;ndig war.<\/p>\n<p>Auch der Urlaub ist nat&uuml;rlich immer ein Thema bei Andy Borg &ndash; er denkt in dem Schlager &bdquo;<strong>In San Marino geht die Sonne auf<\/strong>&ldquo; an &bdquo;<em>tausend bunte<\/em> Pillen &ndash; &auml;&auml;&auml;h <em>Blumen<\/em>&ldquo;, die ihn daran erinnern, dass das Leben sch&ouml;n sein kann. Nach Jogi L&ouml;w, der gerne mal Qualifikationsspiele in dem kleinen Land bestreitet und Ralph Siegel, der dort ja Eurovisions-Asyl erhalten hat, gilt nun auch f&uuml;r Andy: &bdquo;<em>Das l&auml;dt uns heute ein &ndash; nur zum Gl&uuml;cklichsein<\/em>&ldquo; &ndash; vielleicht eine Alternative zum T&uuml;rkei-Urlaub? (&bdquo;<em>Nur der Mann im Mond schaute zu<\/em>&ldquo; &ndash; Diskretion ist also schon mal garantiert dort&hellip;). Der vom Erfolgsgespann Busse\/Rupprich geschriebene (das Booklet nennt Jean Frankfurter als Song-Autoren, das scheint mir aber falsch zu sein &ndash; vielleicht kann jemand Licht ins Dunkel bringen?) &nbsp;Titel wurde &uuml;brigens bereits 1991 erstmals auf dem Album &bdquo;Ich sag es mit Musik&ldquo; ver&ouml;ffentlicht.<\/p>\n<p>In puncto &bdquo;<strong>Christine und ich<\/strong>&ldquo; erfahren wir: &bdquo;<em>Ich tat nichts ohne sie &ndash; sie tat nichts ohne mich<\/em>&ldquo;. Der Schlager d&uuml;rfte einen Weltrekord in musikalischen Modulationen brechen k&ouml;nnen &ndash; in einem Schlager gef&uuml;hlte sechs Tonarten hat man auch nicht alle Tage. Der romantische Andy holte laut seiner Aussage Fr&ouml;sche aus dem Teich und warf sie wieder rein. Wer da keinen &bdquo;Frosch in den Hals&ldquo; kriegt, muss schon ein grober Klotz sein.. &Uuml;brigens &ndash; schon 1987 ging es bei Andy um Christine. Die frisch gek&uuml;rte Gema-Preistr&auml;gerin Irma Holder schrieb den Text des Liedes, das damals noch &bdquo;Gib acht auf Christine&ldquo; hie&szlig; (B-Seite des Hits &bdquo;Mama Domenica&ldquo;). (Im Booklet ist f&auml;lschlicherweise Jean Frankfurter als Textdichter des Liedes genannt, den Text schrieb aber Irma Holder).<\/p>\n<p>Fast 40 Jahre ist es her, dass die Trompeten feurig auf Udo J&uuml;rgens&rsquo; &bdquo;Buenos Dias Argentina&ldquo; eingestimmt haben. Im fr&ouml;hlichen daran leicht angelehnten Sound pr&auml;sentiert uns Andy seine Eigenkomposition &bdquo;<strong>&Uuml;ber den D&auml;chern von Florenz<\/strong>&ldquo;. Musikalisch ein bisschen an den Juliane-Werding-Klassiker &bdquo;Drei Jahre lang&ldquo; erinnert der Discofox-Song &bdquo;<strong>Immer, wenn ich bei Dir bin<\/strong>&ldquo;, der vom gro&szlig;en Christian Bruhn komponiert wurde.<\/p>\n<p>Der n&auml;chste Titel, &bdquo;<strong>Wenn in Rom sch&ouml;n die Rosen bl&uuml;h&rsquo;n<\/strong>&ldquo;, komponiert vom Betreiber der Webseite schlagerkomponist.eu Hannes Marold, &nbsp;l&auml;utet geografisch ein absolutes Highlight der neuen Borg-CD ein: Das Duett mit dem &bdquo;Ex-Flipper&ldquo; Olaf &ndash; Andy und Olaf nahmen sich gemeinsam eines Flippers-Klassikers an: &bdquo;<strong>Sie will einen Italiener<\/strong>&ldquo;.&nbsp; Witzig: Es wurde nach meinem Eindruck das Original-Arrangement aus dem Jahr 2001 verwendet; der Duett-Titel findet sich auch auf Olafs Erfolgsalbum &bdquo;Du bist wie Champagner&ldquo;. (Die Flippers haben den Song 2001 auf der CD &bdquo;Das muss doch Liebe sein&ldquo; erstmals ver&ouml;ffentlicht).<\/p>\n<p>Ein &bdquo;Lied f&uuml;r alle Mamas&ldquo; &ndash; der &bdquo;etwas andere Muttertagssong&ldquo; setzt den Schlussakkord des 2017er Werks des nimmerm&uuml;den Andy Borg: &bdquo;<strong>Das hast Du jetzt davon<\/strong>&ldquo; &#8211; &bdquo;<em>Ich bin so gern Dein Sohn &ndash; das hast Du jetzt da-von<\/em>&ldquo;. Da macht Andy sich nat&uuml;rlich standesgem&auml;&szlig; fein. Andy Borg goes Volksmusik &ndash; aber er ist das Gegenteil eines &bdquo;Volks-Rock&rsquo;n&rsquo;Rollers&ldquo;, er gibt eher den Traditionalisten mit seinem Lied zum Muttertag, das er schon im Fr&uuml;hjahr des letzten Jahres als Digital-Single ver&ouml;ffentlicht hatte.<\/p>\n<p>Unglaubliche f&uuml;nfunddrei&szlig;ig Jahre nach seinem kometenhaften Aufstieg in der Hochzeit der Neuen deutschen Welle bleibt Andy Borg seiner Linie konsequent treu und interpretiert klassische Schlager. Auf seine kr&auml;ftige und angenehme Stimme kann er sich dabei immer verlassen &ndash; das gilt im Livegesch&auml;ft genau so wie im Studio. Der Erfolg gibt dem sympathischen S&auml;nger recht &ndash; seine letzte Studio-LP &bdquo;San Amore&ldquo; schaffte es 2014 bis auf Platz 40 in die Verkaufscharts, in seiner &ouml;sterreichischen Heimat ging es sogar in die Top-5. Die teilweise bissigen Kommentare wird der geborene Wiener aufgrund seines Humors sicher verschmerzen, denn: &bdquo;Was sich neckt, das liebt sich&ldquo;&hellip;.<\/p>\n<p>Stephan Imming, 05.04.2017<br \/>http:\/\/www.mcpsound.at<br \/>http:\/\/andy-borg.de\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Passend zum humorvollen Interpreten hat der smago! Kolumnist augenzwinkernde Zeilen zur neuen CD des beliebten S\u00e4ngers geschrieben &#8230;:\u00a0 Mit Meeresrauschen<\/p>\n","protected":false},"author":2,"featured_media":67331,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[29],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/67330"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=67330"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/67330\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/67331"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=67330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=67330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=67330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}