{"id":67213,"date":"2017-04-08T00:00:00","date_gmt":"2017-04-08T00:00:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=67213"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"DIE-TOTEN-HOSEN-Ihr-brandneuer-67212","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/deutsch-rock\/DIE-TOTEN-HOSEN-Ihr-brandneuer-67212\/","title":{"rendered":"DIE TOTEN HOSEN <br \/>Ihr brandneuer Song hei\u00dft &quot;Unter den Wolken&quot;!"},"content":{"rendered":"<p>Der Song soll auf das lange erwarteten, neue Albums &#8222;Laune der Natur&#8220; einstimmen!\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">F&uuml;nf Jahre ist es her, da erschien von den Toten Hosen im M&auml;rz 2012 &bdquo;Tage wie diese&ldquo; als erste Single-Auskopplung des Albums &bdquo;Ballast der Republik&ldquo;.<\/p>\n<p>Was folgte, ist, wie man so sch&ouml;n sagt, Geschichte: Fast eine Million verkaufter Alben, Vierfach-Platin f&uuml;r das Album, F&uuml;nffach-Gold f&uuml;r die Single, das achte Nummer Eins-Album und eine Nummer Eins-Single zur gleichen Zeit, weit &uuml;ber eine Million Zuschauer auf einer der gr&ouml;&szlig;ten Tourneen, die dieses Land je gesehen hat: Die Jahre 2012 und 2013 hatten es in sich f&uuml;r Die Toten Hosen.<\/p>\n<p>Nun erscheint mit &bdquo;Unter den Wolken&ldquo; die erste Single des lange erwarteten, neuen Albums &bdquo;Laune der Natur&ldquo; und sie steht in bester Tradition der gro&szlig;en Hits der Toten Hosen: hochmelodi&ouml;se, zeitgem&auml;&szlig;e und zeitlose Rockmusik, gleichzeitig treffender Kommentar zur Gegenwart.<\/p>\n<p>Die angek&uuml;ndigten 15 Lieder des neuen Werks im Longplayformat versprechen eine gro&szlig;e thematische Bandbreite: Das Leben wird gefeiert, Trauer wird verarbeitet, Humor darf nicht fehlen und trotzdem will man den Blick f&uuml;r die aktuellen politischen Geschehnisse nicht verlieren. &bdquo;Unter den Wolken&ldquo; ist die perfekte Einstimmung darauf.<\/p>\n<p>JKP (Textvorlage)<br \/>http:\/\/www.jkp.de\/<br \/>http:\/\/www.dietotenhosen.de\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Song soll auf das lange erwarteten, neue Albums &#8222;Laune der Natur&#8220; einstimmen!\u00a0 F&uuml;nf Jahre ist es her, da erschien<\/p>\n","protected":false},"author":2,"featured_media":67214,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[5],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/67213"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=67213"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/67213\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/67214"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=67213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=67213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=67213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}