{"id":67078,"date":"2017-04-12T19:18:00","date_gmt":"2017-04-12T19:18:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=67078"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"KLUBBB3-TV-Tipp-KLUBBB3-heuern-67077","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/schlager\/KLUBBB3-TV-Tipp-KLUBBB3-heuern-67077\/","title":{"rendered":"KLUBBB3 <br \/>TV-Tipp: KLUBBB3 heuern Ostersonntag auf dem &quot;Traumschiff&quot; an!"},"content":{"rendered":"<p>Sehen Sie HIER ein Teaser-Video &#8230;:\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">KLUBBB3 ist am Ostersonntag in der Jubil&auml;umsfolge von &bdquo;Das Traumschiff&ldquo; zu sehen! Als erste Band &uuml;berhaupt sind KLUBBB3 nicht nur auf der B&uuml;hne des Traumschiffes zu sehen, sondern schl&uuml;pfen zum 35-j&auml;hrigen Jubil&auml;um der ZDF-Erfolgsserie sogar in eigene Rollen und stellen damit auch ihre schauspielerischen Qualit&auml;ten unter Beweis.<br \/>\n&nbsp;<br \/>\nDer Grund f&uuml;r die Dreharbeiten mit KLUBBB3 ist gewisserma&szlig;en die Einl&ouml;sung eines alten Versprechens: Florian Silbereisen versprach dem verstorbenen &nbsp;&bdquo;Traumschiff&ldquo;-Produzenten Wolfgang Rademann in einem sehr privaten Rahmen, dass er einmal mitspielen werde. Als dann vor einigen Monaten die Anfrage kam, mussten die drei Jungs nicht lange &uuml;berlegen. Vollends begeistert von den Dreharbeiten auf hoher See wurde anschlie&szlig;end der Titel &bdquo;Auf dem Traumschiff&ldquo; aufgenommen, der auf dem aktuellen Gold- und Nr.1-Album &bdquo;Jetzt geht&acute;s richtig los!&ldquo; von KLUBBB3 zu h&ouml;ren ist.<br \/>\n&nbsp;<br \/>\nOstersonntag hei&szlig;t es nun &bdquo;Ahoi, Herr Kapit&auml;n&ldquo; wenn KLUBBB3 auf dem ZDF-&bdquo;Traumschiff&ldquo; einchecken und gemeinsam mit Kapit&auml;n Victor Burger (Sascha Hehn) &uuml;ber die Meere schippern. Die internationale Schlagerband spielt auf dem Traumschiff drei Angestellte der MS Amadea, die im Schiffsrumpf versteckt ihre Gesangsk&uuml;nste zeigen. Diese bleiben aber nicht lange verborgen, da sie von Kreuzfahrtdirektor Oskar Schifferle, gespielt von Harald Schmidt, entdeckt werden.&nbsp;Als ein Show-Act ausf&auml;llt, kommt die Gesangsentdeckung gerade recht. Die drei werden spontan als Ersatz engagiert&hellip;<\/p>\n<p><iframe loading=\"lazy\" allowfullscreen=\"\" frameborder=\"0\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/7VGgLYXDkl4\" width=\"560\"><\/iframe> &nbsp;<\/p>\n<p>\n<em>Foto-Credit: Universal Music<\/em><\/p>\n<p>Electrola, a division of Universal Music GmbH (Textvorlage)<br \/>http:\/\/www.universal-music.de\/company\/umg\/electrola<br \/>http:\/\/www.universal-music.de\/klubbb3\/home<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sehen Sie HIER ein Teaser-Video &#8230;:\u00a0 KLUBBB3 ist am Ostersonntag in der Jubil&auml;umsfolge von &bdquo;Das Traumschiff&ldquo; zu sehen! Als erste<\/p>\n","protected":false},"author":2,"featured_media":67079,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[29],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/67078"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=67078"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/67078\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/67079"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=67078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=67078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=67078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}