{"id":65176,"date":"2017-06-02T00:00:00","date_gmt":"2017-06-02T00:00:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=65176"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"UTA-BRESAN-Heute-02062017-MDR-F-65175","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/ost-schlager\/UTA-BRESAN-Heute-02062017-MDR-F-65175\/","title":{"rendered":"UTA BRESAN <br \/>Heute (02.06.2017), MDR FERNSEHEN: &quot;Musik f\u00fcr Sie&quot;!"},"content":{"rendered":"<p>&#8222;Mit Uta Bresan unterwegs in der Altmark&#8220; \/\/ 20:15 Uhr &#8211; 21:45 Uhr!\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">Mit einem Sack voller Musikw&uuml;nsche reist Uta Bresan diesmal in den &auml;u&szlig;ersten Norden des Sendegebietes, in die Altmark. Ein &uuml;ber 1.500 km langes Radwandernetz, sch&ouml;nste Reitwanderrouten und unber&uuml;hrte Naturparadiese bieten frische Luft und Entschleunigung pur. Die Bewohner malerischer altm&auml;rkischer D&ouml;rfer lassen sich durch nichts aus der Ruhe bringen und leben in hanseatischer Gelassenheit.<\/p>\n<p>UTA BRESAN erkundet die Region auf dem Fahrrad, im Pferdewagen, auf einem Quad und zu Fu&szlig;. Sie besucht das n&ouml;rdlichste Elbedorf im Sendegebiet Wahrenberg, wo alles im Zeichen des Storches steht, nirgendwo in Sachsen-Anhalt gibt es eine gr&ouml;&szlig;ere Storchendichte. Hier geh&ouml;rt es zum guten Ton, seine eigene Storchenfamilie auf dem Dach zu haben und f&uuml;r sie zu sorgen.<\/p>\n<p>Au&szlig;erdem ist die Altmark der Traum vieler Pferdenarren. Nichtreiterin Uta Bresan geht kurzerhand mit Pferd und Wagen auf Tour und trifft so auf einen der letzten Fischer am Arendsee. Unterwegs findet sie heraus, was das d&auml;nische K&ouml;nigshaus mit der Altmark verbindet, was es mit Kuhschwanzbier auf sich hat und durchstreift die Hansestadt Tangerm&uuml;nde.<\/p>\n<p>Auf die &quot;gr&uuml;ne Wiese mit Zukunft&quot;, wie die Altmark sich selbst bezeichnet, folgen Uta Bresan auch in dieser &quot;Musik f&uuml;r Sie&quot;-Ausgabe wieder einige der beliebtesten S&auml;ngerinnen und S&auml;nger Deutschlands und erf&uuml;llen die W&uuml;nsche der Zuschauer: u.a. Maite Kelly, DJ &Ouml;tzi, Nicole, Feuerherz, Nina Lizell, Mitch Keller und Linda Feller.<\/p>\n<p>\n<em>Foto-Credit: MDR \/ Marco Prosch<\/em><\/p>\n<p>MDR (Textvorlage)<\/p>\n<p>http:\/\/www.uta-bresan.de\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8222;Mit Uta Bresan unterwegs in der Altmark&#8220; \/\/ 20:15 Uhr &#8211; 21:45 Uhr!\u00a0 Mit einem Sack voller Musikw&uuml;nsche reist Uta<\/p>\n","protected":false},"author":2,"featured_media":65177,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[25],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/65176"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=65176"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/65176\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/65177"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=65176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=65176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=65176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}