{"id":31053,"date":"2015-03-13T00:00:00","date_gmt":"2015-03-13T00:00:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=31053"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"Leider-geil-De-Lancaster-RMX-Download-M-31052","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/musik\/Leider-geil-De-Lancaster-RMX-Download-M-31052\/","title":{"rendered":"&#8222;Leider geil (De Lancaster RMX)  (Download-Maxi)&#8220; von Frank Lukas"},"content":{"rendered":"<p>V\u00f6:13.03.2015<!-more-><\/p>\n<p style=\"text-align: justify;\">Nachdem mit &quot;Intensiv&quot; das 3. Studioalbum des K&uuml;nstlers ver&ouml;ffentlicht wurde, folgt nun die n&auml;chste Single-Auskopplung aus dem Hitalbum: &quot;Leider geil&quot; im neuen &quot;De Lancaster Remix&quot;.<\/p>\n<p>Der Titel konnte als Vorab-Auskopplung im vergangenen Jahr f&uuml;r viel Aufsehen sorgen und brachte Frank Lukas u.a. viel Sympathie bei seinem Auftritt w&auml;hrend der J&ouml;rg Bausch Gala in der Arena Oberhausen. Der coole Refrain wurde bereits bei der zweiten Wiederholung lauthals mitgesungen.<\/p>\n<p>In der Hit-Schmiede De Lancaster (die aktuell mit dem Mix zum Andreas Martin Titel &bdquo;Unter dem Regenbogen&ldquo; die deutschen Discotheken-Charts st&uuml;rmen) war man der Meinung, dass der Titel noch wesentlich mehr Potential hat und verpasst ihm einen treibenden, zeitgem&auml;&szlig;en Sound.<\/p>\n<p>&bdquo;Leider geil&ldquo;, eine mitrei&szlig;ende Nummer mit rockigem Gitarrensound, leicht einpr&auml;gsamen und frechem Text! Frank Lukas, ein sympathischer, charismatischer S&auml;nger mit himmelblauen strahlenden Augen und das De Lancaster Team mit der Sp&uuml;rnase f&uuml;r neue Hits und &quot;leider geile&quot; Sounds&hellip;<\/p>\n<p>Die Nummer hat alles, was ein echter Hit ben&ouml;tigt!<\/p>\n<p>B\u00fcro Frank Lukas &#8211; Musik Promotion Prager, Conny Prager (Textvorlage)<br \/>http:\/\/www.meiselmusic.de\/<br \/>http:\/\/www.frank-lukas.com\/<br \/>http:\/\/www.frank-lukas.com\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>V\u00f6:13.03.2015 Nachdem mit &quot;Intensiv&quot; das 3. Studioalbum des K&uuml;nstlers ver&ouml;ffentlicht wurde, folgt nun die n&auml;chste Single-Auskopplung aus dem Hitalbum: &quot;Leider<\/p>\n","protected":false},"author":2,"featured_media":31054,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[35],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/31053"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=31053"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/31053\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/31054"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=31053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=31053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=31053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}