{"id":265944,"date":"2026-09-01T23:59:47","date_gmt":"2026-09-01T21:59:47","guid":{"rendered":"https:\/\/smago.de\/ws2\/?p=265944"},"modified":"2026-09-01T09:34:29","modified_gmt":"2026-09-01T07:34:29","slug":"mandy-bischof-mandy-bischof-meldet-sich-mit-maria-tanz-zurueck","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/schlager\/mandy-bischof-mandy-bischof-meldet-sich-mit-maria-tanz-zurueck\/","title":{"rendered":"MANDY BISCHOF <br>Mandy Bischof meldet sich mit &#8222;Maria tanz&#8220; zur\u00fcck!"},"content":{"rendered":"<p>Mandy Bischof ist &#8222;der Mann hinter dem unvergesslichen Titel &#8218;Sag Dankesch\u00f6n mit roten Rosen'&#8220;, teilt seine Plattenfirma mit!<!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">MANDY BISCHOF, der Mann hinter dem unvergesslichen Titel \u201eSag Dankesch\u00f6n mit roten Rosen\u201c, begeistert seit 1982 die Herzen seiner Fans. Dieser Titel, der zum Synonym f\u00fcr Gem\u00fctlichkeit und stimmungsvolles Beisammensein geworden ist, markierte den Beginn einer beeindruckenden Karriere. Niemand ahnte damals, dass dieses Liedchen zu einem wahren Evergreen avancieren w\u00fcrde.<\/p>\n<p style=\"text-align: justify;\">Trotz der Jahre und der Herausforderungen, die ein schwerer Unfall f\u00fcr ihn mit sich brachte, ist Mandy Bischof immer noch\u00a0 hochmotiviert\u00a0 und ver\u00f6ffentlicht kontinuierlich neue Titel. Seine treue und gro\u00dfe Fan-Gemeinde hat ihn in diesen schweren Zeiten unterst\u00fctzt und auch bei seinem Comeback vor einigen Jahren mit Begeisterung begr\u00fc\u00dft.<\/p>\n<p style=\"text-align: justify;\">Nun ist seine neue Single \u201eMaria tanzt\u201c erschienen. Der Titel ist ein mitrei\u00dfender Latino-Schlager mit einem Groove, der zum Tanzen und Mitsingen einl\u00e4dt. Gespickt mit fetten Bl\u00e4ser-S\u00e4tzen und spanischen Gitarren macht er richtig Freude.<\/p>\n<p style=\"text-align: justify;\">Die Refrain-Zeilen strotzen vor Lebensfreude: \u201eOh Maria, komm tanz mit mir, die ganze Welt dreht sich nur hier. Isabella lacht dazu, So\ufb01a ruft: \u201eIch will noch mehr, will sein wie du!\u201c Camilla, Valentina &#8211; alle sind dabei, heute Nacht sind wir sorgenfrei. Dreh dich, dreh dich, halt dich fest, weil das Leben uns tanzen l\u00e4sst! Oh Maria, oh Maria, dein L\u00e4cheln ist wie Sonnenschein. Wenn du tanzt, dann bleibt die Zeit stehen, und jeder will im Rhythmus sein!\u201c.<\/p>\n<p style=\"text-align: justify;\">\u201eMaria tanzt\u201c verspricht, die Herzen seiner Fans zu erobern und f\u00fcr unvergessliche Momente auf der Tanz\ufb02\u00e4che zu sorgen. Mandy Bischof beweist mit diesem Titel einmal mehr seine musikalische Klasse und seine unb\u00e4ndige Lebensfreude.<\/p>\n<p>Mandy Bischof ist mit nicht weniger als 13 Geschwistern aufgewachsen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mandy Bischof ist &#8222;der Mann hinter dem unvergesslichen Titel &#8218;Sag Dankesch\u00f6n mit roten Rosen&#8217;&#8220;, teilt seine Plattenfirma mit!<\/p>\n","protected":false},"author":2,"featured_media":265945,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[29],"tags":[5383],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/265944"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=265944"}],"version-history":[{"count":3,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/265944\/revisions"}],"predecessor-version":[{"id":265948,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/265944\/revisions\/265948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/265945"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=265944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=265944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=265944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}