{"id":263379,"date":"2026-07-15T15:24:59","date_gmt":"2026-07-15T13:24:59","guid":{"rendered":"https:\/\/smago.de\/ws2\/?p=263379"},"modified":"2026-07-15T15:24:59","modified_gmt":"2026-07-15T13:24:59","slug":"francine-jordi-neue-single-nur-fuer-eine-sommernacht-ab-17-07-2026-erhaeltlich","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/pop-schlager\/francine-jordi-neue-single-nur-fuer-eine-sommernacht-ab-17-07-2026-erhaeltlich\/","title":{"rendered":"FRANCINE JORDI <br>Neue Single &#8222;Nur f\u00fcr eine Sommernacht&#8220; ab 17.07.2026 erh\u00e4ltlich!"},"content":{"rendered":"<p style=\"text-align: justify;\">Ein ganz hei\u00dfer Anw\u00e4rter auf den Sommerhit des Jahres!<br \/>\n<!--more--><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Ist die neue Single von <strong>FRANCINE JORDI<\/strong> der Sommerhit des Jahres? Mit ihrem neuen Song <strong>\u201eNur f\u00fcr eine Sommernacht\u201c<\/strong> pr\u00e4sentiert der Schweizer Superstar einen mitrei\u00dfenden Sommersong voller Leidenschaft und Leichtigkeit. Spanische Gitarren treffen auf moderne Schlager-Pop-Elemente und feurige Einfl\u00fcsse des Lambada \u2013 eine unwiderstehliche Mischung, die sofort Lust auf Sonne, Strand und durchtanzte N\u00e4chte macht.<\/p>\n<p style=\"text-align: justify;\">Der Song startet mit einer warmen, sofort mitrei\u00dfenden Atmosph\u00e4re und zieht den H\u00f6rer direkt in einen intensiven Sommermoment voller Spannung und Emotion. Im Zentrum steht die Begegnung zweier Menschen, bei der ein einziger Augenblick gen\u00fcgt, um Gef\u00fchle unausweichlich werden zu lassen. Mit jeder Zeile entfaltet sich eine Geschichte \u00fcber eine fl\u00fcchtige Begegnung, die f\u00fcr einen einzigen Moment die Zeit stillstehen l\u00e4sst. Barfu\u00df im Sand, ein langer Blick, knisternde Leidenschaft \u2013 <strong>Francine Jordi<\/strong> erz\u00e4hlt von einer Sommernacht, die f\u00fcr immer unvergessen bleibt.<\/p>\n<p style=\"text-align: justify;\">Mit einer eing\u00e4ngigen Lambada-Melodie, s\u00fcdlichem Flair und einem Refrain, der sofort im Ohr bleibt, verbindet <strong>\u201eNur f\u00fcr eine Sommernacht\u201c<\/strong> romantische Sehnsucht mit tanzbarer Leichtigkeit. Entstanden ist der Song in einer sommerlichen Studiosession mit dem bekannten Produzenten Paul Falk.<\/p>\n<p style=\"text-align: justify;\"><strong>Francine Jordi<\/strong> beweist einmal mehr ihr Gesp\u00fcr f\u00fcr starke Melodien und emotionale Geschichten. <strong>\u201eNur f\u00fcr eine Sommernacht\u201c<\/strong> ist ein Song voller Fernweh, Leidenschaft und Lebensfreude \u2013 und damit das perfekte Must-have f\u00fcr jede Sommerparty, jede Urlaubs-Playlist und jeden unvergesslichen Sommermoment.<\/p>\n<p style=\"text-align: justify;\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Francine Jordi \u2013 Live:<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>19.07.2026 &#8211; Pfullendorf (D) \u2013 Schlagersommer Pfullendorf<\/p>\n<p>31.07.2026 &#8211; Riederalp (CH) \u2013 Riederalp Kulturfestival<\/p>\n<p>08.08.2026 &#8211; St. Stephan (CH) \u2013 Volks- und Schlager Festival<\/p>\n<p>28.08.2026 &#8211; Rubigen (CH) \u2013 Schlagerabend<\/p>\n<p>20.09.2026 &#8211; Corban (CH) \u2013 Cerfestival 2026<\/p>\n<p>03.10.2026 &#8211; Monswiller (FR) \u2013 Le Nico Names Schlagerfest<\/p>\n<p>07.10.2026 &#8211; Serfaus-Fiss-Ladis (AT) \u2013 Goldene Herbstkl\u00e4nge<\/p>\n<p>07.11.2026 &#8211; Pore\u010d (HR) \u2013 Herbststadl Pore\u010d<\/p>\n<p>03.12.2026 &#8211; Gunzenhausen (D) \u2013 Klingende Bergweihnacht<\/p>\n<p>05.12.2026 &#8211; Grafenrheinfeld (D) \u2013 Klingende Bergweihnacht<\/p>\n<p>06.12.2026 &#8211; Bad Saulgau (D) \u2013 Klingende Bergweihnacht<\/p>\n<p>10.12.2026 &#8211; \u00d6hringen (D) \u2013 Klingende Bergweihnacht<\/p>\n<p>11.12.2026 &#8211; Laupheim (D) \u2013 Klingende Bergweihnacht<\/p>\n<p>12.12.2026 &#8211; Mosbach (D) \u2013 Klingende Bergweihnacht<\/p>\n<p>13.12.2026 &#8211; Bad Mergentheim (D) \u2013 Klingende Bergweihnacht<\/p>\n<p>18.12.2026 &#8211; Landau in der Pfalz (D) \u2013 Klingende Bergweihnacht<\/p>\n<p>19.12.2026 &#8211; Lohr am Main (D) \u2013 Klingende Bergweihnacht<\/p>\n<p>20.12.2026 &#8211; G\u00fcnzburg (D) \u2013 Klingende Bergweihnacht<\/p>\n<p>21.12.2026 &#8211; Neustadt an der Weinstra\u00dfe (D) \u2013 Klingende Bergweihnacht<\/p>\n<p>22.12.2026 &#8211; Bad Orb (D) \u2013 Klingende Bergweihnacht<\/p>\n<p>27.12.2026 &#8211; Bad Krozingen (D) \u2013 Klingende Bergweihnacht<\/p>\n<p>27.12.2026 &#8211; B\u00fchlertal (D) \u2013 Klingende Bergweihnacht<\/p>\n<p>28.12.2026 &#8211; Baiersbronn (D) \u2013 Klingende Bergweihnacht<\/p>\n<p>28.12.2026 &#8211; Balingen (D) \u2013 Klingende Bergweihnacht<\/p>\n<p>29.12.2026 &#8211; Friedrichshafen (D) \u2013 Klingende Bergweihnacht<\/p>\n<p>29.12.2026 &#8211; Singen (D) \u2013 Klingende Bergweihnacht<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>&#8222;Nur f\u00fcr eine Sommernacht&#8220; &#8211; 3:03 <\/strong><\/p>\n<p>(Composer Lyricist Francine Jordi, Paul Falk, Katharina Schwarz;<\/p>\n<p>Publishers: Falk Family Music Publishing Edition, Frakus Musikverlag, Schedler Musikverlag GmbH)<\/p>\n<p><strong>Produced by: Paul Falk<\/strong><br \/>\n(P)+(C): 2026 Francine Jordi under exclusive license to Heart of Berlin, a label of Musicstarter GmbH &amp; Co. KG<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong><a href=\"https:\/\/www.promojukebox.com\/mlgdel\/?e=V3NyU3NaTlJSUXppQlRIb1VQR3RFZXdGdkthVERkZzFQSms5UVBVWnNIOD0%3D&amp;c=82824622&amp;p=GKMQZMEA3N9MAHQT&amp;checkcode=43f3b9a66900bf33&amp;urlcc=ffafad1bcabce859&amp;acc=ampyTDlZbldqNHJJNXdBMGYwNFVoTktRTGREZjV3OTRadWRFVHBVUDBOUT0%3D\">www.francinejordi.ch<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/www.promojukebox.com\/mlgdel\/?e=V3NyU3NaTlJSUXppQlRIb1VQR3RFZXdGdkthVERkZzFQSms5UVBVWnNIOD0%3D&amp;c=82824622&amp;p=GKMQZMEA3N9MAHQT&amp;checkcode=43f3b9a66900bf33&amp;urlcc=f822cd3c262d156f&amp;acc=cjlkNE1Yc2xUSnBHZys3WjF1dDg5Q2hkcVk5TlF4MzlDQXJkZWVodUIybFFYQnFobERrUUc1SFpRTUNvM2diOA%3D%3D\">www.instagram.com\/francinejordi\/<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/www.promojukebox.com\/mlgdel\/?e=V3NyU3NaTlJSUXppQlRIb1VQR3RFZXdGdkthVERkZzFQSms5UVBVWnNIOD0%3D&amp;c=82824622&amp;p=GKMQZMEA3N9MAHQT&amp;checkcode=43f3b9a66900bf33&amp;urlcc=26e1e3282899bd8e&amp;acc=TnZBcEZnMy9kNEpIUENtUm9sMkRwN3l0U0lhVklhR0FGSDc5ZmxSQ1Q5T1V2QVBiTDVWTlZGM2Z2QVFiQTQ5Yw%3D%3D\">www.facebook.com\/francinejordi.offiziell<\/a><\/strong><\/p>\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"<p>Ein ganz hei\u00dfer Anw\u00e4rter auf den Sommerhit des Jahres!<\/p>\n","protected":false},"author":2,"featured_media":263381,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[28,39],"tags":[202],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/263379"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=263379"}],"version-history":[{"count":1,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/263379\/revisions"}],"predecessor-version":[{"id":263382,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/263379\/revisions\/263382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/263381"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=263379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=263379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=263379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}