{"id":240135,"date":"2025-04-11T22:39:20","date_gmt":"2025-04-11T20:39:20","guid":{"rendered":"https:\/\/smago.de\/ws2\/?p=240135"},"modified":"2025-04-11T22:42:40","modified_gmt":"2025-04-11T20:42:40","slug":"offizielle-deutsche-charts-gfk-entertainment-zartmann-besiegt-elton-john","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/pop\/offizielle-deutsche-charts-gfk-entertainment-zartmann-besiegt-elton-john\/","title":{"rendered":"&#8222;OFFIZIELLE DEUTSCHE CHARTS&#8220; (Gfk Entertainment) <br>Zartmann besiegt Elton John!"},"content":{"rendered":"<div class=\"mod-articlesnews__item\">\n<p>Die &#8222;Sch\u00f6nhauser EP&#8220; holt Platz 1 der Album-Charts! Bei den Singles landet Zartmann auf der Zwei &#8230;:<\/p>\n<\/div>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Selbst Superstar Elton John muss klein beigeben, wenn \u00dcberflieger Zartmann seine neue EP pr\u00e4sentiert. Der Berliner wird zum Chart-Mann und f\u00fchrt erstmals die Offiziellen Deutschen Album-Charts, ermittelt von GfK Entertainment, an. &#8222;Sch\u00f6nhauser&#8220; kommt mal melancholisch, mal leichtf\u00fc\u00dfig daher und beinhaltet u. a. den Nummer-eins-Hit &#8222;Tau mich auf&#8220; sowie die Kollaborationen &#8222;Sch\u00f6nhauser&#8220; (mit Gustav) und &#8222;Lass es gehen&#8220; (mit Max Raabe).<\/p>\n<p style=\"text-align: justify;\">Auch Elton John hat Gefallen an einer Zusammenarbeit gefunden. &#8222;Who Believes In Angels?&#8220; entstand gemeinsam mit US-Singer-Songwriterin Brandi Carlile und flattert an die zweite Stelle. Soundt\u00fcftler DJ Koze (&#8222;Music Can Hear Us&#8220;) sorgt hinter Jazeek (&#8222;Most Valuable Playa&#8220;, drei) f\u00fcr experimentelle Elektro-Kl\u00e4nge auf Rang vier. Ebenfalls in der Top 10 deb\u00fctieren HipHopper PA Sports (&#8222;Parham&#8220;, f\u00fcnf), die Death-Metal-Band Benediction (&#8222;Ravage Of Empires&#8220;, sieben) sowie die bislang nur bei Konzerten erh\u00e4ltliche Rockabilly-Ska-Platte &#8222;Nummus Cecidit&#8220; von Die \u00c4rzte.<\/p>\n<p style=\"text-align: justify;\">In den Single-Charts feiert Rapper Jazeek (&#8222;Akon&#8220;) einen eindrucksvollen Start-Ziel-Sieg und l\u00f6st Vorwochensieger Zartmann (&#8222;Tau mich auf&#8220;, jetzt auf zwei) an der Spitze ab. Bronze holt Oimaras Party-Hit &#8222;Wackelkontakt&#8220;. Trotz des Songtitels ist Nina Chuba alles andere als &#8222;Unsicher&#8220;, denn die S\u00e4ngerin schnellt direkt auf Position f\u00fcnf. Neben dem Duett &#8222;Aye&#8220; (Nimo &amp; AMO, acht) \u00fcberzeugt au\u00dferdem Ed Sheerans aktueller Track &#8222;Azizam&#8220; (zw\u00f6lf).<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><em>Die Offiziellen Deutschen Charts werden von GfK Entertainment im Auftrag des Bundesverbandes Musikindustrie (BVMI) ermittelt. Sie decken 90 Prozent aller Musikverk\u00e4ufe ab und sind das zentrale Erfolgsbarometer f\u00fcr Industrie, Medien und Musikfans. Basis der Hitlisten sind die Verkaufs- bzw. Nutzungsdaten von ca. 2.600 H\u00e4ndlern\/Filialen s\u00e4mtlicher Absatzwege. Dazu z\u00e4hlen der station\u00e4re Handel, E-Commerce-Anbieter, Download-Portale und Streaming-Plattformen.<\/em><\/p>\n<div class=\"mod-articlesnews__item\" style=\"text-align: justify;\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die &#8222;Sch\u00f6nhauser EP&#8220; holt Platz 1 der Album-Charts! Bei den Singles landet Zartmann auf der Zwei &#8230;:<\/p>\n","protected":false},"author":2,"featured_media":240136,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[27],"tags":[145],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/240135"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=240135"}],"version-history":[{"count":3,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/240135\/revisions"}],"predecessor-version":[{"id":240139,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/240135\/revisions\/240139"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/240136"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=240135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=240135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=240135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}