{"id":239674,"date":"2025-03-29T00:00:26","date_gmt":"2025-03-28T23:00:26","guid":{"rendered":"https:\/\/smago.de\/ws2\/?p=239674"},"modified":"2025-03-29T00:11:25","modified_gmt":"2025-03-28T23:11:25","slug":"thomas-anders-sings-modern-talking-auf-tournee-nach-gigantischem-chart-erfolg-eine-emotionale-zeitreise-in-die-80er-jahre","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/schlager\/thomas-anders-sings-modern-talking-auf-tournee-nach-gigantischem-chart-erfolg-eine-emotionale-zeitreise-in-die-80er-jahre\/","title":{"rendered":"THOMAS ANDERS sings MODERN TALKING <br>Auf Tournee nach gigantischem Chart-Erfolg \u2013 eine emotionale Zeitreise in die 80er Jahre!"},"content":{"rendered":"<p>Ein besonderes Highlight der Show ist der innovative Einsatz moderner Technologie!<br \/>\n<!--more--><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Zum 40-j\u00e4hrigen Jubil\u00e4um von Modern Talking \u00fcberrascht <strong>Thomas Anders <\/strong>seine Fans <strong>im M\u00e4rz 2026 <\/strong>mit einer spektakul\u00e4ren <strong>Deutschland- Tournee<\/strong>, die die unvergesslichen Hits des legend\u00e4ren Pop-Duos sowie weitere Klassiker der 80er Jahre feiert. Die \u201e<strong>THOMAS ANDERS sings MODERN TALKING-Tour\u201c <\/strong>ist nicht nur (s)eine liebevolle Hommage an die Musik eines der beliebtesten und pr\u00e4gendsten Musikjahrzehnte, sondern auch eine Premiere f\u00fcr die sensationellen Neuaufnahmen der ersten sechs Modern-Talking-Alben. Damit ist der K\u00fcnstler der erste seiner Art, der sein komplettes Fr\u00fchwerk neu interpretiert und damit auf Tour geht!<\/p>\n<p style=\"text-align: justify;\">Der <strong>Pre-Sale <\/strong>startet <strong>ab sofort <\/strong>unter <a href=\"https:\/\/www.eventim.de\/artist\/thomas-anders\/thomas-anders-sings-modern-talking-2305569\/\"><strong>eventim.de<\/strong><\/a> und der <strong>allgemeine Ticket- Vorverkauf <\/strong>ab dem <strong>31.03.2025 <\/strong>um 12:00 Uhr an allen bekannten Vorverkaufsstellen. <strong>Jetzt Tickets <\/strong>sichern f\u00fcr dieses einmalige Konzerterlebnis!<\/p>\n<p style=\"text-align: justify;\">Thomas Anders, eine der bis heute gr\u00f6\u00dften Ikonen der 80er Jahre, feierte nach dem endg\u00fcltigen Modern-Talking-Split im Sommer 2003 als Solok\u00fcnstler international gro\u00dfe Chart- und Tournee-Erfolge mit seiner Musik. Der 62-j\u00e4hrige Vollblutmusiker hat seinen Weg als S\u00e4nger und Entertainer gemacht, unsterblich aber bleibt der unverwechselbare Modern Talking-Sound, zu dem bis heute weltweit getanzt wird. \u00dcber 125 Millionen Tontr\u00e4ger hat das Kult-Duo in aller Welt verkauft, mehr als 300 Millionen H\u00f6rer j\u00e4hrlich erreicht die Musik aktuell auf den Streaming Portalen. Mit ihren unz\u00e4hligen Hits f\u00fcllten und f\u00fcllen sie \u00fcberall die Dancefloors \u2013 und wurden zu sprichw\u00f6rtlichen \u201cPlatin-Kings of Gro\u00dfraumdisco\u201c!<\/p>\n<p style=\"text-align: justify;\">Thomas Anders, bekannt als die Stimme von Modern Talking, hat die Hits der ersten sechs Alben unter dem Titel \u201eTHOMAS ANDERS sings MODERN TALKING\u201c neu aufgenommen. Bereits die erste Ver\u00f6ffentlichung (Label: STARS by Edel)<\/p>\n<p style=\"text-align: justify;\">\u201eThe 1st Album\u201c schoss auf Anhieb in die Top 5 der deutschen Albumcharts. Diese Neuinterpretationen in modernem Dolby-Atmos-Sound gepaart mit den ikonischen Kl\u00e4ngen der 80er Jahre sind seine Hommage an die gemeinsame Zeit mit Modern Talking und w\u00fcrdigen die gro\u00dfartigen Songs, die Bohlen geschrieben und Anders gesungen haben. Nach dem Erscheinen des ersten Albums am 07. M\u00e4rz 2025, das gleich hoch in die Charts eingestiegen ist, folgen im Laufe dieses Jahres f\u00fcnf weitere Album-Ver\u00f6ffentlichungen, die sowohl ikonische Hits als auch neue Songs im Stil von Modern Talking enthalten.<\/p>\n<p style=\"text-align: justify;\">Diese Neuaufnahmen haben Anders zu dieser Tournee inspiriert, da sie nicht nur die Nostalgie der Fans ansprechen, sondern auch die M\u00f6glichkeit bieten, die Musik von Modern Talking in einem modernen Kontext zu pr\u00e4sentieren und neue sowie bestehende Fans zu begeistern.<\/p>\n<p style=\"text-align: justify;\">In seiner \u00fcber 40-j\u00e4hrigen Musiklaufbahn begeistert Thomas Anders Millionen von Fans in der Show- und Musikbranche. Seine Konzerte sind ein Erlebnis voller Emotionen und Stimmungen, und seine faszinierende Ausstrahlung schafft eine stilvolle N\u00e4he zu seinem Publikum.<\/p>\n<p style=\"text-align: justify;\">Nat\u00fcrlich pr\u00e4sentiert er alle Hits von Modern Talking im Rahmen seiner Tour &#8211; aber auch andere zeitlose Songs seines Lieblingsjahrzehnts, die das Flair der 80er Jahre perfekt einfangen.<\/p>\n<p style=\"text-align: justify;\">Jetzt geht Thomas Anders einen Schritt weiter: Ein besonderes Highlight der Show ist der innovative Einsatz moderner Technologie. \u00dcber eine beeindruckende Videowall wird zum ersten Mal der j\u00fcngere Thomas aus der glorreichen Modern-Talking-\u00c4ra KI-generiert als Duett- Partner des heutigen Thomas gezeigt. Diese einzigartige Performance verbindet Vergangenheit und Gegenwart auf eine Weise, die das Publikum in Staunen versetzen wird.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Dabei sein, wenn Thomas Anders auf Deutschlandtour geht und eine unvergessliche Show erleben, die die Magie der 80er Jahre wieder aufleben l\u00e4sst und gleichzeitig die aufregenden Neuinterpretationen seiner gr\u00f6\u00dften Hits im modernen Soundgewand pr\u00e4sentiert!<\/p>\n<p style=\"text-align: justify;\">Jetzt rechtzeitig Tickets sichern, um Teil dieses au\u00dfergew\u00f6hnlichen Musikerlebnisses zu sein!<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>Der Pre-Sale startet ab sofort unter <\/strong><a href=\"https:\/\/www.eventim.de\/artist\/thomas-anders\/thomas-anders-sings-modern-talking-2305569\/\"><strong>eventim.de<\/strong><\/a> <strong>und der allgemeine Ticket- Vorverkauf ab dem 31. M\u00e4rz 2025 um 12 Uhr unter <\/strong><a href=\"https:\/\/www.myticket.de\/de\/\"><strong>myticket.de<\/strong><strong>,<\/strong><\/a> <a href=\"https:\/\/www.eventim.de\/artist\/thomas-anders\/thomas-anders-sings-modern-talking-2305569\/\"><strong>eventim.de<\/strong><\/a> <strong>und an allen bekannten Vorverkaufsstellen.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>THOMAS ANDERS \u201esings MODERN TALKING\u201c<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Deutschlandtour 2026<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"95\"><strong>Tag<\/strong><\/td>\n<td width=\"104\"><strong>Datum<\/strong><\/td>\n<td width=\"85\"><strong>Ort<\/strong><\/td>\n<td width=\"227\"><strong>Halle<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"95\">Donnerstag<\/td>\n<td width=\"104\"><strong>19.03.2026<\/strong><\/td>\n<td width=\"85\">Berlin<\/td>\n<td width=\"227\">Uber Eats Music Hall<\/td>\n<\/tr>\n<tr>\n<td width=\"95\">Freitag<\/td>\n<td width=\"104\"><strong>20.03.2026<\/strong><\/td>\n<td width=\"85\">Hamburg<\/td>\n<td width=\"227\">CCH1<\/td>\n<\/tr>\n<tr>\n<td width=\"95\">Dienstag<\/td>\n<td width=\"104\"><strong>24.03.2026<\/strong><\/td>\n<td width=\"85\">Stuttgart<\/td>\n<td width=\"227\">Liederhalle Beethoven-Saal<\/td>\n<\/tr>\n<tr>\n<td width=\"95\">Mittwoch<\/td>\n<td width=\"104\"><strong>25.03.2026<\/strong><\/td>\n<td width=\"85\">Leipzig<\/td>\n<td width=\"227\">QUARTERBACK Immobilien Arena<\/td>\n<\/tr>\n<tr>\n<td width=\"95\">Donnerstag<\/td>\n<td width=\"104\"><strong>26.03.2026<\/strong><\/td>\n<td width=\"85\">D\u00fcsseldorf<\/td>\n<td width=\"227\">Mitsubishi Electric Halle<\/td>\n<\/tr>\n<tr>\n<td width=\"95\">Freitag<\/td>\n<td width=\"104\"><strong>27.03.2026<\/strong><\/td>\n<td width=\"85\">Frankfurt<\/td>\n<td width=\"227\">Jahrhunderthalle<\/td>\n<\/tr>\n<tr>\n<td width=\"95\">Samstag<\/td>\n<td width=\"104\"><strong>28.03.2026<\/strong><\/td>\n<td width=\"85\">Wien<\/td>\n<td width=\"227\">Raiffeisen Halle im Gasometer<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Weitere Informationen unter <strong><a href=\"https:\/\/www.thomas-anders.com\/\">thomas-anders.com<\/a><\/strong> und <a href=\"https:\/\/www.kuenstlershow.de\/thomas-anders\/\"><strong>kuenstlershow.de<\/strong><\/a>!<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_239675\" aria-describedby=\"caption-attachment-239675\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img decoding=\"async\" loading=\"lazy\" class=\"size-large wp-image-239675\" src=\"https:\/\/smago.de\/ws2\/wp-content\/uploads\/2025\/03\/ThomasAnders_singsMT_The1stAlbum_Cover_Layer-800x800.jpg\" alt=\"\" width=\"800\" height=\"800\" srcset=\"https:\/\/smago.de\/ws2\/wp-content\/uploads\/2025\/03\/ThomasAnders_singsMT_The1stAlbum_Cover_Layer-800x800.jpg 800w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2025\/03\/ThomasAnders_singsMT_The1stAlbum_Cover_Layer-522x522.jpg 522w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2025\/03\/ThomasAnders_singsMT_The1stAlbum_Cover_Layer-150x150.jpg 150w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2025\/03\/ThomasAnders_singsMT_The1stAlbum_Cover_Layer-768x768.jpg 768w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2025\/03\/ThomasAnders_singsMT_The1stAlbum_Cover_Layer-1536x1536.jpg 1536w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2025\/03\/ThomasAnders_singsMT_The1stAlbum_Cover_Layer-2048x2048.jpg 2048w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2025\/03\/ThomasAnders_singsMT_The1stAlbum_Cover_Layer-272x272.jpg 272w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2025\/03\/ThomasAnders_singsMT_The1stAlbum_Cover_Layer-600x600.jpg 600w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2025\/03\/ThomasAnders_singsMT_The1stAlbum_Cover_Layer-130x130.jpg 130w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2025\/03\/ThomasAnders_singsMT_The1stAlbum_Cover_Layer-445x445.jpg 445w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2025\/03\/ThomasAnders_singsMT_The1stAlbum_Cover_Layer-190x190.jpg 190w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2025\/03\/ThomasAnders_singsMT_The1stAlbum_Cover_Layer-290x290.jpg 290w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-239675\" class=\"wp-caption-text\"><em>Foto-Credit: Chartswards.com<\/em><\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ein besonderes Highlight der Show ist der innovative Einsatz moderner Technologie!<\/p>\n","protected":false},"author":2,"featured_media":239675,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[29,39],"tags":[48],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/239674"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=239674"}],"version-history":[{"count":1,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/239674\/revisions"}],"predecessor-version":[{"id":239676,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/239674\/revisions\/239676"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/239675"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=239674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=239674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=239674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}