{"id":171046,"date":"2021-09-10T00:04:24","date_gmt":"2021-09-09T22:04:24","guid":{"rendered":"https:\/\/smago.de\/ws2\/?p=171046"},"modified":"2021-09-10T00:04:54","modified_gmt":"2021-09-09T22:04:54","slug":"sotiria-mit-mein-herz-ist-ihr-ein-sehr-authentisches-und-tolles-album-gelungen","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/pop\/sotiria-mit-mein-herz-ist-ihr-ein-sehr-authentisches-und-tolles-album-gelungen\/","title":{"rendered":"SOTIRIA <br>Mit \u201eMein Herz\u201c ist ihr ein sehr authentisches und tolles Album gelungen!"},"content":{"rendered":"<p><strong>Respekt \u2013 das ist eine<\/strong><strong>s der besten &#8222;Schlager&#8220;alben des Jahres!<br \/>\n<\/strong><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Das Album startet mit der Vorab-Single \u201e<strong>Einfach nur ein M\u00e4dchen<\/strong>\u201c, mit dem SOTIRIA so etwas wie einen Imagewechsel vollzogen hat \u2013 eine Art Emanzipation ihrer EISBLUME- bzw. GRAF-Vergangenheit ist sp\u00fcrbar. Hilfreich ist hier sicher, dass SOTIRIA ihre Lieder inzwischen alle selber (mit) schreibt. In diesem Fall hat sie mit BAHAR HENSHEL eine geniale Textdichterin zur Seite gehabt. Die Vorab-Single handelt davon, sich zu Selbstzweifeln oder eigenen Unzul\u00e4nglichkeiten zu bekennen. \u2013 Ein toller Einstieg in ein bemerkenswertes Album.<\/p>\n<p style=\"text-align: justify;\">Verbotene Leidenschaft \u2013 in \u201e<strong>Heute Nacht<\/strong>\u201c ein ewig junge und beliebtes Schlagerthema. \u201e\u2026brauch ich n kleines bisschen mehr von dir\u201c, so fordert SOTIRIA ihre Gegen\u00fcber zur S\u00fcnde auf. \u2013 \u201eEs gibt nichts zu bereuen\u201c, so denkt SOTIRIA, die sich in diesem Lied ganz als Frau mit Bed\u00fcrfnissen gibt und diesmal eine andere Facette von sich preisgibt als die des M\u00e4dchens. Eine Nummer, die wahrscheinlich clubtauglich ist \u2013 tanzbare Beats und leidenschaftliches schweres Atmen machen auch musikalisch klar, worum es in ihrem hei\u00dfen Song geht.<\/p>\n<p style=\"text-align: justify;\">Den Titelsong \u201e<strong>Herz<\/strong>\u201c stellte SOTIRIA beim Free ESC von STEFAN RAAB vor. In dem Lied geht es darum, dass man rational manchmal Gef\u00fchle gerne ausblenden m\u00f6chte, das Herz das aber nicht zulassen kann und eine innere Zerrissenheit entsteht. Schade, dass SOTIRIA damit beim Free-ESC nicht besser platziert war \u2013 f\u00fcr unseren Geschmack hat sie ihren Song sehr gut pr\u00e4sentiert.<\/p>\n<p style=\"text-align: justify;\">Das ganze Album \u201eHerz\u201c wirkt authentisch und autobiografisch. Inhaltlich ganz im Stile gro\u00dfer franz\u00f6sischer Chansons\u00e4ngerinnen (\u201eJe ne regrette rien\u201c) steht SOTIRIA selbstbewusst zu dem, was sie im Leben getan hat: \u201e<strong>Ich bereue nichts<\/strong>\u201c \u2013 auch wenn sie sich \u201efast verloren hat\u201c und \u201eNacht mit Tr\u00e4nen\u201c verlebt hat \u2013 das hat sie \u201ezu dem gemacht, was ich jetzt bin\u201c.<\/p>\n<p style=\"text-align: justify;\">Ein ernstes Thema behandelt SOTIRIA im Lied \u201e<strong>Wahre Liebe<\/strong>\u201c. Es geht darin darum, wie schwer es ist, nach einigen Verletzungen dennoch an die wahre Liebe zu glauben. Mit zunehmenden negativen Erfahrungen und Entt\u00e4uschungen entstehen nun einmal Bindungs\u00e4ngste \u2013 ein Ph\u00e4nomen der heutigen Zeit, nach dem immer noch perfekten Partner zu suchen. \u201eIch hab Angst for dieser Einsamkeit\u201c, \u201eIch hab verlernt zu f\u00fchlen\u201c \u2013 das sind nat\u00fcrlich intime Gedanken, die SOTIRIA in ihrem Lied zum Ausdruck bringt, sie will sich wieder \u00f6ffnen, nicht verschlie\u00dfen und vergeben \u2013 auch mit tiefsinnigen Texten gibt die K\u00fcnstlerin eine gute Figur ab \u2013 ein G\u00e4nsehaut-Song.<\/p>\n<p style=\"text-align: justify;\">Trotz eines erneut ernsten Themas ist \u201e<strong>Ich schau nach oben<\/strong>\u201c, in dem es um den Tod der geliebten Oma geht, eine Uptempo-Nummer: \u201eIch wollt dir nur sagen, dank dir wei\u00df ich, dass Liebe niemals stirbt\u201c. W\u00e4hrend sie in ihrem \u00e4lteren Song \u201eIch lass dich frei\u201c noch in tiefer Trauer war, hat sie nun \u201eein L\u00e4cheln im Gesicht\u201c, wenn sie an ihre verehrte Oma zur\u00fcckblickt, die sicher stolz auf ihre Enkelin ist.<\/p>\n<p style=\"text-align: justify;\">In \u201e<strong>Zur\u00fcck ans Meer<\/strong>\u201c beschreibt SOTIRIA eine Alltagsflucht. Ganz im Sinne der Kollgen von SANTIANO, die gemeinsam mit der h\u00fcbschen S\u00e4ngerin in der GIOVANNI-ZARRELLA-Show auftreten, beschreibt sie ihren Sehnsuchtsort, das Meer, das laut ihrer Aussage ein \u201eGef\u00fchl von Frieden und Freiheit vermittelt\u201c. Sie will \u201eRichtung Horizont entfliehen, dahin wo der Wind weht \u2013was h\u00e4lt uns noch hier?\u201c. Ein melancholisches Sehnsuchtslied der etwas anderen Art.<\/p>\n<p style=\"text-align: justify;\">\u201eWoran sollen wir noch glauben in dieser kalten schnellen Welt?\u201c, \u201eWem sollen wir noch vertrauen, wenn jeder sich f\u00fcr wichtig h\u00e4lt?\u201c \u2013 schon in den ersten Zeilen wird klar, worum es in dieser nicht leichten Zeit geht, in der man den \u201eFunken in der Dunkelheit\u201c bewahren soll.<\/p>\n<p style=\"text-align: justify;\">In \u201e<strong>Schalt dein Herz an<\/strong>\u201c geht es darum, weniger auf \u00e4u\u00dfere Einfl\u00fcsse zu h\u00f6ren, sondern auf sein eigenes Herz zu h\u00f6ren: \u201eDie Liebe soll regieren\u201c, das ist die \u00dcberzeugung von SOTIRIA.<\/p>\n<p style=\"text-align: justify;\">Recht melancholisch geht es in \u201e<strong>Bleib nur<\/strong>\u201c zu. Das Lied beschreibt eine krisengebeutelte Beziehung, in der es darum geht, entweder \u00fcberzeugt zur Beziehung zu stehen (\u201ewenn du wirklich an uns glaubst\u201c) und sein \u201eHerz offen\u201c zu legen. Ein krampfhaftes Festhalten ist nicht gut (\u201eBleib nur, wenn du wirklich an uns glaubst\u201c). Auch das ein ehrliches Lied \u2013 das Thema wird vielen Fans bekannt vorkommen.<\/p>\n<p style=\"text-align: justify;\">Mit \u201e<strong>Vielleicht<\/strong>\u201c greift SOTIRIA erneut ein Thema auf, das sie schon einmal in einem Song verarbeitet hat (\u201eWer bist du?\u201c). Es geht um das schwierige Verh\u00e4ltnis zu ihrem leiblichen Vater, dessen griechische Herkunft \u00fcbrigens dazu f\u00fchrte, dass sie beim Free-ESC f\u00fcr Griechenland antreten durfte \u2013 leider auch in dem Punkt kein \u201eHappy End\u201c. \u201eVielleicht ist alles, was ich h\u00f6ren muss, nur ein echtes \u201atut mir leid\u2019 \u2013 ein Lied, das so richtig unter die Haut geht. Musikalisch scheint SOTIRIA das sch\u00f6ne Lied \u201eBig Big Girl\u201c zu m\u00f6gen, nebenbei bemerkt\u2026<\/p>\n<p style=\"text-align: justify;\">So ganz weg kommt die charismatische S\u00e4ngerin nicht von UNHEILIG. Mit niemand geringerem als GIOVANNI ZARRELLA hat sie dessen Riesenhit \u201e<strong>Geboren um zu leben<\/strong>\u201c in einer deutsch-italienischen Fassung aufgenommen \u2013 gut vorstellbar, dass die Aufnahme in der GIOVANNI-ZARRELLA-Show erklingen wird.<\/p>\n<p style=\"text-align: justify;\">Die melancholische Ballade \u201e<strong>Liebe auf Zeit<\/strong>\u201c handelt davon, dass es Beziehungen gibt, bei denen die Leidenschaft gro\u00df war und dennoch irgendwie von vorneherein klar war, dass es nur \u201eLiebe auf Zeit\u201c war, also die zeitliche Begrenzung von vorneherein unausgesprochen beiden Beteiligten klar war. \u201eWenn sich die T\u00fcr f\u00fcr immer schlie\u00dft\u201c, bleibt oft nur ein \u201esch\u00f6nes St\u00fcck Erinnerung\u201c \u2013 mehr nicht, wenn \u201edas letzte L\u00e4cheln l\u00e4ngst verhallt\u201c ist. Auch hier sind UNHEILIG-Anleihen von der Produktion her wahrnehmbar.<\/p>\n<p style=\"text-align: justify;\">Das Lied \u201e<strong>F\u00fcr immer wir zwei<\/strong>\u201c deutet vom Titel her vielleicht an, dass es sich um eine Liebesbeziehung handelt \u2013 und irgendwie stimmt das auch, allerdings nicht im erotischen Sinne. Es geht um SOTIRIAs beste Freundin namens LINA (in diesem Fall darf der Name genannt werden), der die Berlinerin mit ihrem Lied ein Denkmal singt \u2013 aus Dankbarkeit f\u00fcr offensichtlich bedingungslosen Zusammenhalt. Wohl dem, der so jemanden zum Freund bzw. zur Freundin hat. \u201eWir sind ein Leben lang vereint \u2013 immer wir zwei\u201c \u2013 ein sch\u00f6ner Freundschaftsbeweis f\u00fcr LINA\u2026<\/p>\n<p style=\"text-align: justify;\">In \u201e<strong>Vielleicht<\/strong>\u201c geht es darum, wie SOTIRIA sich wieder nach oben begeben hatte, nachdem sie am Boden war und depressiven Stimmungen ausgesetzt war. Auch dieses unbequeme Thema hat sie nicht tabuisiert.<\/p>\n<p style=\"text-align: justify;\">\u201e<strong>Einer dieser Tage<\/strong>\u201c ist eine Uptempo-Nummer, die optimistisch Zeiten feiert, an denen wir die \u201eSorgen nicht sehen\u201c. Ein Song, der sicher in Clubs gut ankommen. Sie will sich in \u201everr\u00fcckten Tr\u00e4umen verlieren\u201c \u2013 melodi\u00f6s und inhaltlich ist der Titel schlageresk gehalten, aber hier passt wohl eher die Bezeichnung \u201eElectroschlager\u201c.<\/p>\n<p style=\"text-align: justify;\">Eine weitere Ballade im UNHEILIG-Stil ist \u201e<strong>Mein Zuhause, das bist du<\/strong>\u201c \u2013 ein sehr sch\u00f6nes Lieblingslied, bei dem sich zwei Stimmen gesucht und gefangen haben \u2013 die markante Stimme des Duettpartners MIKE LEON GROSCH und die herrliche glockenklare Sopranstimme von SOTIRIA \u2013 das passt einfach \u2013 da d\u00fcrfen auch mal Streicher erklingen. Ein sch\u00f6nes Liebeslied.<\/p>\n<p style=\"text-align: justify;\">Eine Clubversion von \u201eHerz\u201c ist ein sch\u00f6ner Bonus der Deluxe-Edition.<\/p>\n<p style=\"text-align: justify;\">\u201e<strong>Mein Weg geht weiter<\/strong>\u201c \u2013 \u201eauf Dunkelheit folgt Licht\u201c. Mit diesem Lied beschreibt SOTIRIA den Optimismus, nach vorne zu schauen nach einer Trennung \u2013 und dennoch sind vergangene Zeiten nicht ganz so leicht abzustreifen. Auch der Titel scheint autobiografische Z\u00fcge zu tragen \u2013 auch wenn \u201eaus gemeinsam allein wird\u201c \u2013 aber: \u201eIch schaff\u2019s auch ohne dich!\u201c.<\/p>\n<p style=\"text-align: justify;\">Sehr sch\u00f6n ist auch die Liveversion von \u201e<strong>Einfach nur ein M\u00e4dchen<\/strong>\u201c \u2013 hier zeigt SOTIRIA ihre Livequalit\u00e4ten beeindruckend.<\/p>\n<p style=\"text-align: justify;\">Es folgen zwei \u00fcberraschende, aber sehr tolle Coverversionen \u2013 SOTIRIA hat sich des ROSENSTOLZ-Klassikers \u201eLachen\u201c angenommen. Ihre Stimme passt sehr gut zum ROSENSTOLZ-Sound. Klar, dass PETER PLATE SOTIRIA auch ein eigenes Lied geschrieben hat: \u201eSpiegel der Zeit\u201c. Mit \u201eNacht voll Schatten\u201c von JULIANE WERDING gibt es einen weiteren Coversong auf die Ohren.<\/p>\n<p style=\"text-align: justify;\">Die Akustikversion von \u201e<strong>Heute Nacht<\/strong>\u201c (Track 2) rundet das Album ab.<\/p>\n<p>Lange mussten wir warten auf das neue Album von SOTIRIA \u2013 aber das Warten hat sich gelohnt. \u201eHerz\u201c ist ein stimmiges Lied, bei dem die K\u00fcnstlerin sich extrem offen und authentisch gibt \u2013 und das merkt man den b\u00e4renstarken Songs an. Vielleicht ist SOTIRIA damit eins der besten Schlageralben des Jahres gelungen.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-large wp-image-171030\" src=\"https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_deluxe-1-800x800.jpg\" alt=\"\" width=\"800\" height=\"800\" srcset=\"https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_deluxe-1-800x800.jpg 800w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_deluxe-1-522x522.jpg 522w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_deluxe-1-150x150.jpg 150w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_deluxe-1-768x768.jpg 768w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_deluxe-1-272x272.jpg 272w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_deluxe-1-600x600.jpg 600w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_deluxe-1-130x130.jpg 130w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_deluxe-1-445x445.jpg 445w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_deluxe-1-190x190.jpg 190w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_deluxe-1-290x290.jpg 290w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_deluxe-1.jpg 1500w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-large wp-image-171031\" src=\"https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_fanbox-1-634x800.jpg\" alt=\"\" width=\"634\" height=\"800\" srcset=\"https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_fanbox-1-634x800.jpg 634w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_fanbox-1-414x522.jpg 414w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_fanbox-1-119x150.jpg 119w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_fanbox-1-768x969.jpg 768w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_fanbox-1-216x272.jpg 216w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_fanbox-1-476x600.jpg 476w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_fanbox-1-103x130.jpg 103w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_fanbox-1-353x445.jpg 353w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_fanbox-1-151x190.jpg 151w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_fanbox-1-230x290.jpg 230w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/09\/sotiria_fanbox-1.jpg 1189w\" sizes=\"(max-width: 634px) 100vw, 634px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Respekt \u2013 das ist eines der besten &#8222;Schlager&#8220;alben des Jahres!<\/p>\n","protected":false},"author":2,"featured_media":171029,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[27],"tags":[404],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/171046"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=171046"}],"version-history":[{"count":3,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/171046\/revisions"}],"predecessor-version":[{"id":171049,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/171046\/revisions\/171049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/171029"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=171046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=171046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=171046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}