{"id":161640,"date":"2021-02-16T00:00:32","date_gmt":"2021-02-15T23:00:32","guid":{"rendered":"https:\/\/smago.de\/ws2\/?p=161640"},"modified":"2021-02-15T23:39:57","modified_gmt":"2021-02-15T22:39:57","slug":"gisela-steineckert-so-entstand-der-kult-hit-als-ich-fortging","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/ost-schlager\/gisela-steineckert-so-entstand-der-kult-hit-als-ich-fortging\/","title":{"rendered":"GISELA STEINECKERT <br>So entstand der Kult-Hit &#8222;Als ich fortging&#8220;!"},"content":{"rendered":"<p style=\"text-align: justify;\">Die 89-j\u00e4hrige Schriftstellerin, Lyrikerin und Textdichterin erinnert sich in der MDR-Talkshow &#8222;Riverboat&#8220; wie folgt &#8230;:<br \/>\n<!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"\" style=\"text-align: justify;\">\n<p><b class=\"\">J\u00f6rg Kachelmann: Haben Sie schon einen Impf-Termin, Frau Steineckert?<\/b><\/p>\n<p>Ja, ich bin da mit der ganzen Familie voran gegangen. Die beiden Termine habe ich jetzt bald und es war alles ganz einfach zu organisieren. Ich habe es schon vorher laut verk\u00fcndet: Wenn es soweit ist &#8211; ich komme sofort impfen. Worauf alle sagten: Was, bist du sicher? Hast du keine Angst? Ich habe mehr Angst, mich nicht impfen zu lassen. Ich muss ehrlich sagen, wenn ich es nicht gemacht h\u00e4tte, w\u00e4re mir ganz beklommen. Ich h\u00e4tte das Gef\u00fchl, meine Pflicht zu verletzen. Die Pflicht meiner Familie und meinen Enkeln gegen\u00fcber, der 4-j\u00e4hrigen Urenkelin gegen\u00fcber und meinen T\u00f6chtern. Ich w\u00fcrde sie damit gef\u00e4hrden. Ich gehe dahin und mache das gerne.<\/p>\n<\/div>\n<div class=\"\" style=\"text-align: justify;\"><b class=\"\">J\u00f6rg Kachelmann: Wie war Ihre erste Begegnung mit Dirk Michaelis und seinem gro\u00dfen Hit \u201eAls ich fortging \u2026\u201c, den Sie getextet haben?<\/b><\/div>\n<div class=\"\" style=\"text-align: justify;\">\n<div class=\"\">\n<p>Unsere erste Begegnung war sehr merkw\u00fcrdig. Bei uns wurde gerade das gro\u00dfe Zimmer gemalert und auf einmal stand da ein junger Mann mit langen Haaren und kurzen Hosen im Raum. Sieht mich sehr selbstbewu\u00dft an und sagte: Du musst mir einen Text auf diese Melodie schreiben. Er dr\u00fcckte mir eine kleine altmodische Kassette in die Hand, dreht sich um und geht. Dann lie\u00df ich das erst einmal 4-5 Wochen liegen. Dachte dann aber selber: Das ist unanst\u00e4ndig. Wenigstens erst einmal anh\u00f6ren, damit ich Gr\u00fcnde habe, es abzulehnen, dann in ein Kuvert zu stecken und ihm zur\u00fcck zu schicken.<\/p>\n<\/div>\n<\/div>\n<div class=\"\" style=\"text-align: justify;\">Und dann habe ich die Kassette so neben meinem Schreibtisch in ein Ger\u00e4t geschoben und vor mir lag wie immer Papier. Mit den ersten T\u00f6nen war die erste Zeile da. Ich kann das nicht erkl\u00e4ren. Es war ein Ph\u00e4nomen. Es gibt das Wunder und das ist bei vielen meiner Lieder so: Alles wird \u00fcberhaupt nichts, wenn es nicht diese EINE Zeile gibt, die von selber singt. Die st\u00e4rker ist als der Schlaf und der Hunger und die Lust, jetzt mal gar nichts zu machen. Diese eine Zeile, die dich nicht in Ruhe l\u00e4\u00dft und immer wieder da ist. Und so war es auch hier. Es war diese erste Zeile \u201eAls ich fortging \u2026\u201c. Da musste ich sagen, was da war und schon sah ich viele Bilder. Die Stra\u00dfe, manchmal Schnee und es kamen Erkenntnisse aus meinem Leben, die ich gerade sehr stark versp\u00fcrte. \u201eNichts ist unendlich &#8211; so sieh das doch ein. Auch die Trauer wird sein\u201c.<\/p>\n<\/div>\n<div class=\"\" style=\"text-align: justify;\"><b class=\"\">\u2026\u00fcber Dirk Michaelis:<\/b><\/div>\n<div class=\"\" style=\"text-align: justify;\">\n<p>Dirk Michaelis ist in mein Leben getreten und hat die Kassette da gelassen. Dann habe ich ihm das Kuvert geschickt und da war der Text drin. Ich wu\u00dfte gar nicht, dass er damals bei der Gruppe \u201eKarussell\u201c der S\u00e4nger war. Ich hatte ihn ja noch nie gesehen. Und dann sah und h\u00f6rte ich das Lied eines Tage auf dem Bildschirm im \u201ePolizeiruf 110\u201c. Sp\u00e4ter habe ich ihn wiedergesehen und es entstand aus uns eine Freundschaft durch die Arbeit. Ja, es ist so: Immer und immer wieder erwartet er wieder einen Text von mir, die ich in laaaaanger Arbeit erstelle. Und dann nimmt er nur einen (lacht). Als ich ihn kennenlernte, habe ich erkannt: Dieser Mensch Dirk Michaelis hat mir gefehlt in meinem Leben.Weil er die Musik machen kann, die meine Texte zum Klingen bringen.<\/p>\n<\/div>\n<div class=\"\" style=\"text-align: justify;\">Ich wollte aber eins noch hinzuf\u00fcgen, das ist mir wichtig: Dieses Lied ist niemals f\u00fcr den Mauerfall geschrieben wurden. Es h\u00e4tte eigentlich sein k\u00f6nnen, aber es wurde nie f\u00fcr den Mauerfall geschrieben.<\/div>\n<div class=\"\" style=\"text-align: justify;\"><b class=\"\"><br \/>\nJ\u00f6rg Kachelmann: Wie schreiben Sie diese vielen Lied-Texte, versetzen Sie sich da in eine Art Trance?<\/b><\/div>\n<div class=\"\" style=\"text-align: justify;\">\n<p>Nein, das ist ehrliche Arbeit. Es ist immer wieder diese eine Zeile, die ganz aufdringlich kommt und mich nicht los l\u00e4\u00dft. Dann frage ich sie: Was willst du? Ich habe gerade etwas ganz anderes vor, will ein buch schreiben oder so. Bis ich dahinter komme, warum sie mir immer wieder einf\u00e4llt. Es kann etwas Erlebtes sein, etwas Gelesenes. Mitten im Leben meist in ganz n\u00fcchternen Situationen, ist da eine Zeile.<\/p>\n<\/div>\n<div><\/div>\n<div><\/div>\n<div><\/div>\n<div>\n<figure id=\"attachment_161641\" aria-describedby=\"caption-attachment-161641\" style=\"width: 480px\" class=\"wp-caption alignnone\"><img decoding=\"async\" loading=\"lazy\" class=\"size-large wp-image-161641\" src=\"https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/02\/steineckert_buch2-480x800.jpg\" alt=\"\" width=\"480\" height=\"800\" srcset=\"https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/02\/steineckert_buch2-480x800.jpg 480w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/02\/steineckert_buch2-313x522.jpg 313w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/02\/steineckert_buch2-90x150.jpg 90w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/02\/steineckert_buch2-768x1280.jpg 768w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/02\/steineckert_buch2-922x1536.jpg 922w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/02\/steineckert_buch2-163x272.jpg 163w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/02\/steineckert_buch2-360x600.jpg 360w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/02\/steineckert_buch2-78x130.jpg 78w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/02\/steineckert_buch2-267x445.jpg 267w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/02\/steineckert_buch2-114x190.jpg 114w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/02\/steineckert_buch2-174x290.jpg 174w, https:\/\/smago.de\/ws2\/wp-content\/uploads\/2021\/02\/steineckert_buch2.jpg 1014w\" sizes=\"(max-width: 480px) 100vw, 480px\" \/><figcaption id=\"caption-attachment-161641\" class=\"wp-caption-text\"><em>Foto-Credit: Das Neue Berlin<\/em><\/figcaption><\/figure>\n<\/div>\n<div class=\"\" style=\"text-align: justify;\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die 89-j\u00e4hrige Schriftstellerin, Lyrikerin und Textdichterin erinnert sich in der MDR-Talkshow &#8222;Riverboat&#8220; wie folgt &#8230;:<\/p>\n","protected":false},"author":2,"featured_media":161641,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[25],"tags":[1950],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/161640"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=161640"}],"version-history":[{"count":3,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/161640\/revisions"}],"predecessor-version":[{"id":161644,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/161640\/revisions\/161644"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/161641"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=161640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=161640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=161640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}