{"id":124800,"date":"2019-01-05T00:00:16","date_gmt":"2019-01-04T23:00:16","guid":{"rendered":"https:\/\/smago.de\/?p=124800"},"modified":"2019-01-04T21:32:36","modified_gmt":"2019-01-04T20:32:36","slug":"ich-bin-ein-star-holt-mich-hier-raus-diese-zwoelf-kandidaten-ziehen-ins-dschungelcamp-2019","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/schlager\/ich-bin-ein-star-holt-mich-hier-raus-diese-zwoelf-kandidaten-ziehen-ins-dschungelcamp-2019\/","title":{"rendered":"&#8222;ICH BIN EIN STAR &#8211; HOLT MICH HIER RAUS!&#8220; <br>Diese zw\u00f6lf Kandidaten ziehen ins Dschungelcamp 2019!"},"content":{"rendered":"<p>Am 11.01.2019 geht der Dschungelspa\u00df wieder los &#8230;:<br \/>\n<!--more--><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">\n<div class=\"text\" style=\"text-align: justify;\">\n<p>Am Freitag, 11. Januar, um 21.15 Uhr startet \u201eIch bin ein Star \u2013 Holt mich hier raus!\u201c in die 13. Staffel (16 Folgen), in der zw\u00f6lf Stars im fernen Australien um die Dschungelkrone 2019 k\u00e4mpfen. Begleitet werden sie in gewohnt s\u00fcffisanter Weise von unserem bew\u00e4hrten Moderatoren-Duo Sonja Zietlow und Daniel Hartwich. Auch Dr. Bob ist wieder dabei und wird unsere Stars auf die Dschungelpr\u00fcfungen vorbereiten.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div class=\"text\" style=\"text-align: justify;\">\n<p>&nbsp;<\/p>\n<\/div>\n<div class=\"text\">\n<p style=\"text-align: justify;\"><strong>Und das sind die zw\u00f6lf Stars, die in der 13. Staffel von \u201eIch bin ein Star &#8211; Holt mich hier raus!\u201c auf Sternejagd gehen werden:<\/p>\n<p><\/strong><\/p>\n<p style=\"text-align: justify;\">Evelyn Burdecki (30): Die ehemalige \u201eBachelor\u201c-Kandidatin geht hochmotiviert ins Camp, eine ausgekl\u00fcgelte Strategie im Kampf um die Dschungelkrone hat sie aber nicht: \u201eAlles, was ich tue, ist ohne Plan. Ich mache immer einfach\u201c, verr\u00e4t die geb\u00fcrtige D\u00fcsseldorferin. Bei \u00f6ffentlichen Auftritten tr\u00e4gt sie vorzugsweise roten Lippenstift. Ob ihr die Optik auch im Dschungelcamp wichtig ist? \u201eJa, ich will nicht so wie ein Lappen aussehen.\u201c<\/p>\n<p>Domenico de Cicco (35): Der Bachelorette-Kandidat m\u00f6chte im Dschungelcamp seine Grenzen austesten und bereitet sich akribisch vor: \u201eIch esse Maden zur Vorbereitung. Die kriegt man in jedem Angelshop. Das ist schon eine Herausforderung.\u201c Auch k\u00f6rperlich geht der Fitness-Fan ideal vorbereitet an den Start: \u201eIch habe f\u00fcr den Dschungel sieben Kilo zugenommen, damit ich eine Basis f\u00fcr die Pr\u00fcfungen habe. Man wird im Camp sehr viel abnehmen.\u201c<\/p>\n<p>Doreen Dietel (44): Die Schauspielerin (\u201eDahoam is Dahoam\u201c) und Caf\u00e9besitzerin findet das Dschungelcamp \u201ecool\u201c und scheut auch nicht vor extremen Situationen zur\u00fcck: \u201eIch freue mich auf jede Pr\u00fcfung und habe Lust darauf. Ich freue mich sogar auf die Essenpr\u00fcfungen. Ich habe als Kind beim Schlachten schon Schweineblut getrunken und H\u00fchnerf\u00fc\u00dfe gegessen.\u201c Doreen ist eigentlich ein Teammensch. Sollte es aber im Team Streit geben, macht sie die klare Ansage: \u201eIch gehe total auf Konfrontation.\u201c<\/p>\n<p>Sandra Kiriasis (43): Die Bob-Olympiasiegerin m\u00f6chte im Dschungelcamp Durchhalteverm\u00f6gen beweisen \u2013 wenn die Zuschauer sie lassen: \u201eIch habe noch nie aufgegeben: Aufgeber gewinnen nie und Gewinner geben nie auf.\u201c Die ehemalige Sportsoldatin (Rang: Stabsfeldwebel) hat ihre Position im Team dabei klar vor Augen: \u201eIch bin der Spie\u00df und die Mutter der Kompanie.\u201c Ob ihre Mit-Camper das auch so sehen werden?<\/p>\n<p>Leila Lowfire (26): Die Sex-Expertin gibt sich angesichts der tropischen Temperaturen im Dschungelcamp entspannt: \u201eIch denke, bei den Temperaturen werde ich schon etwas freiz\u00fcgiger rumlaufen. Ich habe kein Problem mit meinem K\u00f6rper und habe lange damit gearbeitet. Es ist ja auch keine \u00dcberraschung, wie ich nackt aussehe.\u201c Beim Thema \u201eEssenspr\u00fcfungen\u201c setzt sie auf Tempo: \u201eIch w\u00fcrde auf jeden Fall versuchen die Sachen schnell zu essen, damit das Gehirn noch gar nicht realisiert, was man da gerade isst.\u201c<\/p>\n<p>Gisele Oppermann (31): Das Model, das in der dritten Staffel von Germanys Next Topmodel durch tr\u00e4nenreiche Auftritte bekannt wurde, gibt zu: \u201eIch bin schon ein Sensibelchen. Ich jammere auch ganz gerne mal, aber ich kann auch ordentlich austeilen. Wenn mich da jemand angreift, dann lass ich mir das nicht gefallen.\u201c Im Dschungel warten auf Gisele zahlreiche Entbehrungen \u2013 doch besonders ein Verzicht k\u00f6nnte ihr Probleme bereiten: \u201eDrei Tage ohne Zigaretten und dann reicht schon ein falscher Blick, um aus der Haut zu fahren.\u201c<\/p>\n<p>Peter Orloff (74): Der Schlager-Star &amp; Produzent m\u00f6chte im Camp seine sportliche Seite zeigen \u2013 und die Zuschauer zum Mitmachen animieren: \u201eIch will zeigen, dass man mit 74 Jahren auch noch alles machen kann. Wenn ich das kann, dann k\u00f6nnen die Zuschauer das auch. Ich m\u00f6chte beweisen, dass man aus seinem Leben in jeder Phase etwas machen kann. Das soll die Botschaft sein.\u201c In der Gruppe sieht er sich bei Konflikten eher als Vermittler: \u201eIch habe in der Schule gelernt, dass der Frieden so stark ist, wie du selber bist, um ihn zu bewahren.\u201c<\/p>\n<p>Tommi Piper (77): Der Schauspieler und legend\u00e4re Synchronstimme von Alf sieht m\u00f6glichen Entbehrungen im australischen Urwald noch gelassen entgegen: \u201eIch kann von heute auf morgen abgekochtes Wasser trinken.\u201c Sollte sich die Gelegenheit bieten, m\u00f6chte er als Camp-\u00c4ltester eine Andacht zu Ehren der ehemaligen Camp-Insassen halten, die nicht mehr unter uns sind: \u201eWenn ich es durchkriege, halte ich eine Andacht auf alle Verstorbenen. Auf Gunter Gabriel, Rolf Zacher, auf Malle-Jens, aber eigentlich will ich das f\u00fcr Daniel K\u00fcblb\u00f6ck tun. Der hat mich besonders fasziniert.\u201c<\/p>\n<p>Sibylle Rauch (58): Die Erotik-Ikone freut sich auf die Zeit im Camp: \u201eDas ist eine gro\u00dfe Chance und ein tolles Format.\u201c Zu den Herausforderungen, die sie im Camp erwarten, sagt sie: \u201eDurch meine vielen Sch\u00f6nheits-OPs und k\u00fcnstliche Z\u00e4hne sehe ich auch Nachteile. Ich hoffe, dass ich in einer Dschungelpr\u00fcfung z.B. die Fischaugen bei\u00dfen kann. Ganz ehrlich.\u201c Mit ihr anlegen sollten sich ihre Mitstreiter besser nicht: \u201eIch schaue nicht danach aus, aber ich kann auch austeilen.\u201c<\/p>\n<p>Chris T\u00f6pperwien (44): Der aus \u201eGoodbye Deutschland\u201c (VOX) und \u201eDas Sommerhaus der Stars\u201c (RTL) bekannte Currywurstmann blickt vor allem mit Sorge auf die hygienischen Zust\u00e4nde im Dschungelcamp: \u201eIch bin schon ein Verfechter der Sauberkeit. Ich habe da auch einen Fimmel. Viele sagen, dass ich einen Zwang habe: alles muss immer gerade, sauber und steril sein. Das kann man im Dschungel nat\u00fcrlich nicht verlangen. Aber es muss jemanden geben, der eine leitende Funktion hat. Wenn einer neben das Klo schei\u00dft, bin ich der erste, der etwas sagt.\u201c<\/p>\n<p>Felix van Deventer (22): Bei \u201eGute Zeiten, schlechte Zeiten\u201c ist er Jonas Seefeld. F\u00fcr seine Zeit im Camp hat er sich vorgenommen: \u201eIch m\u00f6chte den Leuten zeigen, dass meine Rolle bei GZSZ und Felix komplett unterschiedlich sind.\u201c Panische Angst hat er vor einer flugf\u00e4higen Tierart, die in Dschungelpr\u00fcfungen zumindest bisher noch keine zentrale Rolle gespielt hat: \u201eIch habe mal Batman geguckt, da habe ich Flederm\u00e4use gesehen, bin zuhause umgekippt und hatte einen kleinen epileptischen Anfall. Seitdem habe ich gemerkt: Flederm\u00e4use sind gar nicht mein Ding.\u201c<\/p>\n<p>Bastian Yotta (42): Der selbsternannte Million\u00e4r liebt Herausforderungen. Da ist er im gef\u00e4hrlichsten Dschungel der Welt am richtigen Ort: \u201eG\u00e4nzlich alles ist eine Herausforderung. Auf der Pritsche schlafen, fremde Leute, in der Gruppe agieren, Ekelpr\u00fcfungen, Hitze und Schwei\u00df &#8211; also ist das Camp eine einzige Herausforderung.\u201c Auf dem Weg zum Dschungelk\u00f6nig m\u00f6chte er auch ungewohnte Seiten von sich zeigen: \u201eIch bin \u00fcberzeugt, wenn die Zuschauer mich als Menschen kennenlernen, dass sie \u00fcberrascht sein werden.\u201c<\/p>\n<p style=\"text-align: justify;\">Exklusive Geschichten aus dem Dschungelcamp finden die Fans bei RTL.de, die mit neuem Inhalte-Konzept und Design gl\u00e4nzt. Zum ersten Mal gibt es bei RTL.de auch exklusive News rund um die Geschehnisse am Versace. RTL.de-Chefreporter Sebastian Tews wird den Begleitpersonen und ausgeschiedenen Campern dort auf den Zahn f\u00fchlen. Special Content gibt es au\u00dferdem auch auf der offiziellen Facebook-Seite von &#8222;Ich bin ein Star \u2013 Holt mich hier raus!&#8220; sowie auf dem offiziellen Instagram-Account (@ichbineinstar.rtl) unter #ibes2019. Via WhatsApp k\u00f6nnen sich die Fans brandhei\u00dfe News auch direkt aufs Smartphone holen. Aktuelles und Hintergrundinfos auch \u00fcber Twitter @RTL.de #IBES<\/p>\n<p style=\"text-align: justify;\">Das Dschungelabenteuer gibt es im Livestream und in voller L\u00e4nge im Anschluss an die Sendung bei TVNOW.de oder in der TV-NOW-App zu sehen.<\/p>\n<p style=\"text-align: justify;\">Direkt im Anschluss an IBES startet ab dem 11.1. jeden Abend die Liveshow \u201eIch bin ein Star &#8211; Holt mich hier raus! &#8211; Die Stunde danach\u201c. Die RTLplus-Eigenproduktion ist von Montag bis Freitag bei RTLplus und am Wochenende bei RTL sowie zeitgleich bei TV NOW zu sehen. Beim t\u00e4glichen Talk-Event mit Angela Finger-Erben sind jeden Abend die besten Dschungelkandidaten aus vergangenen Staffeln live im Studio. Die Sendung liefert exklusive Einblicke in das Geschehen im Dschungel, Liveschalten zu den Promis und ihren Begleitern im Hotel Versace, neue Rubriken und verr\u00fcckte Spiele.<\/p>\n<p style=\"text-align: justify;\">Begleitet wird die neue Staffel der RTL-Dschungelshow mit der Single &#8222;WTF (feat. Amber Van Day)&#8220; des K\u00fcnstlers Hugel dank einer Kooperation der IP Deutschland mit Warner Music Central Europe.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Am 11.01.2019 geht der Dschungelspa\u00df wieder los &#8230;:<\/p>\n","protected":false},"author":2,"featured_media":124801,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[29,34,39,128],"tags":[758],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/124800"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=124800"}],"version-history":[{"count":1,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/124800\/revisions"}],"predecessor-version":[{"id":124802,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/124800\/revisions\/124802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/124801"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=124800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=124800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=124800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}