{"id":117931,"date":"2013-03-21T14:14:00","date_gmt":"2013-03-21T14:14:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=117931"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"DAVID-GARRETT-Nach-18-Jahren-w-117930","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/instrumental\/DAVID-GARRETT-Nach-18-Jahren-w-117930\/","title":{"rendered":"DAVID GARRETT <br \/> Nach 18 Jahren wiederentdeckt: David Garrett &#8211; Das &#8222;verlorene&#8220; Album!"},"content":{"rendered":"<p>Heute (Do., 21.03.2013) gibt es bei MyDG einen Track des Albums umsonst&#8230;:\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\"><font color=\"#000000\" face=\"Arial, Helvetica, sans-serif\" size=\"1\" style=\"LINE-HEIGHT: normal; FONT-FAMILY: Arial, Helvetica, sans-serif; COLOR: #000000; FONT-SIZE: 11px\">&bdquo;F&uuml;r mich pers&ouml;nlich ist &sbquo;14&lsquo; die Verbindung zwischen den Aufnahmen, die ich als Kind gemacht habe und den Alben, die ich jetzt als Erwachsener einspiele. Ich bin sehr froh, dass das Album nach so vielen Jahren herauskommt, denn ich glaube, dass damit ein St&uuml;ck weit meine Geschichte zusammenw&auml;chst.&ldquo;<\/p>\n<p>David Garrett im Jahre 2013 &#8211; das sind ausverkaufte S&auml;le, kreischende Fans, wummernde Beats und im Zentrum der Superstar mit seiner Geige.<\/p>\n<p>David Garrett im Jahre 1995 &ndash; das war der j&uuml;ngste jemals exklusiv unter Vertrag genommene K&uuml;nstler bei dem weltweit renommiertesten Klassiklabel Deutsche Grammophon, auf welchem er als Wunderkind sein Plattendeb&uuml;t mit niemand Geringerem als Claudio Abbado feierte.<\/p>\n<p>&bdquo;F&uuml;r mich selbst ist es unglaublich zur&uuml;ckzuschauen und zu sehen, was ich in diesem Alter gemacht habe.&ldquo; Deshalb ist &bdquo;14&ldquo; ein au&szlig;ergew&ouml;hnliches zeitgeschichtliches Dokument, das gleichsam als Momentaufnahme aus dem Jahr 1995 eine wegweisende Station in der Karriere des K&uuml;nstlers beleuchtet. Mit der Ver&ouml;ffentlichung des Albums bekommt der H&ouml;rer die seltene M&ouml;glichkeit, den einst jungen Geiger mit dem heute in aller Welt etablierten Stargeiger zu vergleichen.<\/p>\n<p>&bdquo;&ldquo;&lsquo;14&lsquo; ist eine Momentaufnahme meines Lebens, ein Schnappschuss meiner Geschichte, es zeigt einen wichtigen Teil davon, wer und was ich heute bin. Ich bin erleichtert, dass dieses &bdquo;verlorene&ldquo; Album nun ver&ouml;ffentlicht wird.&ldquo;<\/p>\n<p><em>&bdquo;14&ldquo;: Musik von Paganini, Tartini, Dvor&aacute;k, Schubert, Kreisler, Tschaikowsky, Wieniawski, Elgar, Bruch<\/p>\n<p>David Garrett, Violine, Alexander Markovich, Klavier<\/p>\n<p>Deutsche Grammophon 4790933, Ver&ouml;ffentlichung: 22. M&auml;rz 2013<\/em><\/p>\n<p>Heute gibt es bei <strong><a href=\"http:\/\/my.deutschegrammophon.com\/buzz-material\/details\/74\">HIER<\/a><\/strong> einen Track des Albums umsonst<font size=\"1\">!<\/font><\/font><\/p>\n<p>Universal Music (Textvorlage)<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute (Do., 21.03.2013) gibt es bei MyDG einen Track des Albums umsonst&#8230;:\u00a0 &bdquo;F&uuml;r mich pers&ouml;nlich ist &sbquo;14&lsquo; die Verbindung zwischen<\/p>\n","protected":false},"author":2,"featured_media":117932,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[38],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/117931"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=117931"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/117931\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/117932"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=117931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=117931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=117931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}