{"id":11793,"date":"2018-01-11T00:00:00","date_gmt":"2018-01-11T00:00:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=11793"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"VANESSA-MAI-Vanessa-Mai-und-der-11792","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/pop-schlager\/VANESSA-MAI-Vanessa-Mai-und-der-11792\/","title":{"rendered":"VANESSA MAI<br \/>Vanessa Mai und der goldene Regenbogen!"},"content":{"rendered":"<p>Wissenswertes \u00fcber die &#8222;Gold Edition&#8220; ihres Nr. 1-Albums &#8222;Regenbogen&#8220;!<!-more-><\/p>\n<p style=\"text-align: justify;\">Das neue Jahr ist nur ein paar Tage alt und schon haben die Fans von VANESSA MAI einen Grund, wieder die Korken knallen zu lassen.<\/p>\n<p style=\"text-align: justify;\">Am 12.01.2018 erscheint die &bdquo;Gold Edition&ldquo; von Vanessa&#39;s #1 Album &bdquo;Regenbogen&ldquo;.<\/p>\n<p>Mit vier neuen Titeln (&bdquo;Wo du bist&ldquo;, &bdquo;1.000 Lieder&ldquo;, &bdquo;Irgendwie, Irgendwo, Irgendwann&ldquo;&nbsp; &#8211; eine Coverversion von Nena &#8211;&nbsp; und &bdquo;Solange es dich gibt&ldquo;), sowie insgesamt acht Remixen von &bdquo;Wenn das wirklich Liebe ist&ldquo;, &bdquo;Sch&ouml;nster Moment&ldquo;, &bdquo;Sternenmeer&ldquo;, &bdquo;Echo&ldquo;, &bdquo;Nie wieder&ldquo; und vielen anderen, &uuml;berrascht sie ihre Fans schon fr&uuml;h im neuen Jahr.<\/p>\n<p style=\"text-align: justify;\">Nat&uuml;rlich darf auf der &bdquo;Gold Edition&ldquo;von &bdquo;Regenbogen&ldquo; die gef&uuml;hlvolle Piano-Version sowie der Party taugliche Starchild-Remix von der aktuellen Single &bdquo;Regenbogen&ldquo; nicht fehlen, beides produziert von Felix Gauder.<\/p>\n<p>Doch damit nicht genug. Die Fans bekommen weiters eines der raren DIN A4 Poster und als besonderen Gimmick den Vanessa Mai Early Entry Pass, der allerdings nach dem Zufallsprinzip in insge samt nur jeweils 500 Gold Editionen versteckt ist.<\/p>\n<p>Der Early Entry Pass berechtigt 2 Personen in Verbindung mit g&uuml;ltigen Eintrittskarten bereits den Soundcheck von Vanessa Mai vor dem jeweiligen Konzert der &bdquo;Regenbogen Live Tour 2018&ldquo; mitzuerleben.<\/p>\n<p>Auch die Optik hat f&uuml;r den Fan Sammlerwert. Das eigentlich ros&egrave;farbene Cover wird jetzt in Gold getaucht und in einem hochwertigen Digipack im Handel erscheinen. Auch die CD selbst wird in der limitierten Auflage in edler Goldfarbe gl&auml;nzen.<\/p>\n<p>lanz unlimited communications (Textvorlage)<br \/>http:\/\/www.ariola.de<br \/>https:\/\/www.vanessa-mai.de\/News-Termine-Musik-Bio-Sommerparty-Kontakt.html<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wissenswertes \u00fcber die &#8222;Gold Edition&#8220; ihres Nr. 1-Albums &#8222;Regenbogen&#8220;! Das neue Jahr ist nur ein paar Tage alt und schon<\/p>\n","protected":false},"author":2,"featured_media":11794,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[28],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/11793"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=11793"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/11793\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/11794"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=11793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=11793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=11793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}