{"id":117928,"date":"2013-03-22T00:00:00","date_gmt":"2013-03-22T00:00:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=117928"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"MAXI-ARlAND-Geschaeftsfuehrerw-117927","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/schlager\/MAXI-ARlAND-Geschaeftsfuehrerw-117927\/","title":{"rendered":"MAXI ARlAND <br \/> Gesch\u00e4ftsf\u00fchrerwechsel bei der milian media GmbH!"},"content":{"rendered":"<p>Was sich zum 1. April 2013 \u00e4ndert&#8230;:\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">Zum 1. April 2013 &uuml;bergibt Mike Steffens die Gesch&auml;ftsf&uuml;hrung der <em>milian media GmbH<\/em> an Andrea M&uuml;hlbauer. Als Gesch&auml;ftsf&uuml;hrer der AS EVENTS GmbH und der <em>milian media GmbH<\/em> stellt er einen enorm wachsenden Gesch&auml;ftsumfang beider Unternehmen fest. Daher wird er sich k&uuml;nftig intensiv auf seine Aufgaben bei der <em>AS EVENTS GmbH<\/em> im Konzert- und Veranstaltungsbereich konzentrieren.<\/p>\n<p>Eine weitere enge Zusammenarbeit zwischen beiden Unternehmen wird es auch in Zukunft geben. &quot;Wir veranstalten im Herbst 2013 die Tournee &quot;Wunderland der Tr&auml;ume&quot; mit Maxi Arland, Anita &amp; Alexandra Hofmann und dem Deutschen Showballett Berlin und planen gerade f&uuml;r 2014 eine gro&szlig;e Fr&uuml;hjahrs-Tournee mit Maxi Arland&quot;. Meiner Nachfolgerin, Andrea M&uuml;hlbauer, w&uuml;nsche ich viel Erfolg. Sie konnte in den vergangenen Jahren wichtige Erfahrungen in der Medienbranche sammeln und wird die <em>milian media GmbH<\/em> sicherlich professionell in eine gute Zukunft f&uuml;hren&quot;, erkl&auml;rt Mike Steffens.<\/p>\n<p>Maxi Arland freut sich schon sehr auf die k&uuml;nftigen gemeinsamen Aktivit&auml;ten mit der <em>AS EVENTS GmbH<\/em> im Tourneebereich. &quot;Ich sch&auml;tze Mike Steffens als Mensch und als Gesch&auml;ftspartner sehr und bin ihm f&uuml;r seine gro&szlig;artige Arbeit als Gesch&auml;ftsf&uuml;hrer der <em>milian media GmbH <\/em>unheimlich dankbar. F&uuml;r seinen weiteren beruflichen Weg w&uuml;nsche ich ihm nur das Beste&quot;, so Maxi Arland.<\/p>\n<p>milian media GmbH, Mike Steffens (Textvorlage)<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was sich zum 1. April 2013 \u00e4ndert&#8230;:\u00a0 Zum 1. April 2013 &uuml;bergibt Mike Steffens die Gesch&auml;ftsf&uuml;hrung der milian media GmbH<\/p>\n","protected":false},"author":2,"featured_media":117929,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[29],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/117928"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=117928"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/117928\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/117929"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=117928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=117928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=117928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}