{"id":114163,"date":"2013-07-02T00:00:00","date_gmt":"2013-07-02T00:00:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=114163"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"TRUCK-STOP-UEberragender-guter-114162","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/country\/TRUCK-STOP-UEberragender-guter-114162\/","title":{"rendered":"TRUCK STOP <br \/> \u00dcberragender guter Start f\u00fcr ihr Jubil\u00e4ums-Set &quot;40 Jahre &#8230; geile Zeiten&quot;!"},"content":{"rendered":"<p>Derzeit deutet alles auf einen ausgezeichneten Chart-Entry hin&#8230;:\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">Sie sind &quot;Die Cowboys der Nation&quot; und im Jahr ihres 40-j&auml;hrigen Band-Jubil&auml;ums erfolgreicher und popul&auml;rer denn je&#8230;<\/p>\n<p>Das mit gro&szlig;er Liebe von GLORIELLA Music (Musikproduktion Jack White) zusammengestellte Box-Set (2 CDs + 1 DVD) &quot;40 Jahre &#8230; geile Zeiten&quot; hat einen ganz hervorragenden Start in den Trend-Charts hingelegt.<\/p>\n<p>Am Erstverkaufstag belegten Truck Stop einen schier unglaublichen 13. Platz. Am Samstag waren sie auf Position 61 notiert.<\/p>\n<p>Nach jetzigem Stand der Dinge w&uuml;rden &quot;Die Cowboys von der Waterkant&quot; auf einem unglaublich guten Rang 26 in die deutschen Top 100-Charts einsteigen. Gut, dieses (Zwischen-)Ergebnis wird wohl nicht zu halten sein, da es in der Ver&ouml;ffentlichungswoche leider keine einzige (nennenswerte) TV-Sendung gab und gibt, die das 40-j&auml;hrige Bestehen von Deutschlands Country-Band Nr. 1 zu w&uuml;rdigen bereit gewesen ist (&quot;Das Sommerfest in &Ouml;sterreich&quot; war leider auch bereits &quot;voll&quot;). Umso bemerkenswerter diese mehr als erfreulichen Platzierungen in den deutschen Album Trend-Charts an den ersten beiden Verkaufstagen. Hierzu muss man wissen, dass Truck Stop sowohl am Freitag als auch am Samstag noch vor Jan Smit und dessen (Deutschland-)Comeback-Album &quot;Ich bin da&quot; gelistet waren! Diese Dimension(en) muss man sich erst einmal vorstellen!!!<\/p>\n<p>Die Herren von Truck Stop k&ouml;nnen sich eben in jeder Lebenslage auf ihre treuen Fans verlassen.<\/p>\n<p>Als aktuelle Radio-Single wurde der (neue) Titel &quot;Was f&uuml;r geile Zeiten das doch war&#39;n&quot; ausgew&auml;hlt, der es immerhin bereits bis auf Platz 29 der Airplay Charts Deutschland Konservativ geschafft hatte.&nbsp;&nbsp;<\/p>\n<p>Das Jubil&auml;ums-Set ist ein absolutes &quot;must have&quot; f&uuml;r alle Fans. Hier hat GLORIELLA Music nun wirklich weder Kosten noch M&uuml;hen gescheut und den Fans eine opulente Box geschenkt, die jedes Deutsch Country Fan-Herz schneller schlagen l&auml;sst&#8230; Zudem ist das Preis-Leistungs-Verh&auml;ltnis ein ganz hervorragendes.<\/p>\n<p>Eine ausf&uuml;hrliche Produkt-Beschreibung finden Sie <strong><a href=\"https:\/\/smago.de\/index.php?d=produkte&amp;s=2547\">HIER&#8230;:<\/a><\/strong><\/p>\n<p>Andy Tichler, Chefredakteur www.smago.de<br \/>http:\/\/www.gloriellamusic.de\/<br \/>http:\/\/www.truck-stop.de<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Derzeit deutet alles auf einen ausgezeichneten Chart-Entry hin&#8230;:\u00a0 Sie sind &quot;Die Cowboys der Nation&quot; und im Jahr ihres 40-j&auml;hrigen Band-Jubil&auml;ums<\/p>\n","protected":false},"author":2,"featured_media":114164,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[4],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/114163"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=114163"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/114163\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/114164"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=114163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=114163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=114163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}