{"id":109621,"date":"2013-11-12T00:00:00","date_gmt":"2013-11-12T00:00:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=109621"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"GUNTER-GABRIEL-Titel-Bum-Bum-B-109620","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/country\/GUNTER-GABRIEL-Titel-Bum-Bum-B-109620\/","title":{"rendered":"GUNTER GABRIEL <br \/> Titel &quot;Bum Bum Boris&quot; ab Freitag (15.11.2013) als Download-Track verf\u00fcgbar!"},"content":{"rendered":"<p>&#8222;Das Liebeslied f\u00fcr Boris Becker&#8220; ist als &#8222;Country Rock Version&#8220; und als &#8222;Gospel Rock Version&#8220; verf\u00fcgbar! Mit pers\u00f6nlichem &#8211; jedoch leicht zensierten &#8211; Video-Beitrag von Gunter Gabriel&#8230;:\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">GUNTER GABRIEL war als Ehrengast eingeladen zu der Buchpr&auml;sentation &bdquo;Das Leben ist kein Spiel&ldquo; von Boris Becker. &bdquo;Mach&lsquo; ein bisschen Hintergrundmusik mit deinen Jungs&ldquo;, so Christian Schommers, der Ghostwriter des Buches, &bdquo; und wenn du Lust hast, schreib f&uuml;r den Abend doch &#39;ne Hommage an Boris.&ldquo; Ok, gesagt getan.<\/p>\n<p>Gunter setzte sich mit seinem Freund, dem Liedermacher Timon Hoffmann hin und fertig war das Lied. Der Song kam riesig an, eingebettet in ein h&uuml;bsches, harmloses Countrysong Programm. Jeder der G&auml;ste des Abends bekam im Anschluss eine CD mit 2 Versionen des Songs &bdquo;Bum Bum Boris.&ldquo;<\/p>\n<p>Nur der Star des Abends, war gar nicht so wild auf das Lied. Vielleicht hatte er geglaubt Gabriel w&uuml;rde ihn damit durch den Kakao ziehen. War aber gar nicht Gabriels\/Hoffmanns Absicht.<\/p>\n<p>Alle jubelten &ndash; nur Boris verzog eine gequ&auml;lte Miene. Hier nun die beiden Versionen. Die Facebook-Gemeinde favorisiert die langsamere Country Version mit dem gesprochenen Intro.<\/p>\n<p>Also: Spiel, Satz und Song f&uuml;r Boris Becker.<\/p>\n<p>Gunter Gabriel an die Rundfunk-Redakteur:<em> &quot;Wenn&acute;s in Euer Programm passt, dann nix wie spielen&quot;.<\/em><\/p>\n<p><iframe loading=\"lazy\" allowfullscreen=\"\" frameborder=\"0\" height=\"384\" src=\"\/\/www.youtube.com\/embed\/up9_wDhLuWc\" width=\"512\"><\/iframe><\/p>\n<p>Bluebird Caf\u00e9 Berlin Records (Textvorlage)<br \/>http:\/\/www.bcb-records.de\/<br \/>http:\/\/www.google.de\/url?sa=t&#038;rct=j&#038;q=&#038;esrc=s&#038;frm=1&#038;source=web&#038;cd=1&#038;ved=0CC4QFjAA&#038;url=http%3A%2F%2Fwww.guntergabriel.de%2F&#038;ei=3kaBUv_NLMXWswb_rYHoDg&#038;usg=AFQjCNFVWoXqEDnDPdPsj3NmsBM1qr6CLw&#038;bvm=bv.56146854,d.Yms<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8222;Das Liebeslied f\u00fcr Boris Becker&#8220; ist als &#8222;Country Rock Version&#8220; und als &#8222;Gospel Rock Version&#8220; verf\u00fcgbar! Mit pers\u00f6nlichem &#8211; jedoch<\/p>\n","protected":false},"author":2,"featured_media":109622,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[4],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/109621"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=109621"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/109621\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/109622"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=109621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=109621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=109621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}