{"id":106396,"date":"2014-02-11T00:00:00","date_gmt":"2014-02-11T00:00:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=106396"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"MICHAEL-WENDLER-Charity-Auktio-106395","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/pop-schlager\/MICHAEL-WENDLER-Charity-Auktio-106395\/","title":{"rendered":"MICHAEL WENDLER <br \/> Charity-Auktion (des Wendlers Dschungel-Outfit) erfolgreich beendet!"},"content":{"rendered":"<p>Die &#8222;Dinslakener Tafel&#8220; darf sich \u00fcber einen stattlichen Betrag freuen&#8230;:\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">Die Charity-Auktion von MICHAEL WENDLER f&uuml;r die &quot;Dinslakener Tafel&quot; ist erfolgreich beendet.<\/p>\n<p>Die Auktion bei eBay brachte 1.510,00 Euro f&uuml;r das Dschungel-Outfit und 510,- Euro f&uuml;r den Wendler-Hut, der separat versteigert wurde.<\/p>\n<p>Somit ist der stattliche Betrag von 2.020,00 &euro; f&uuml;r den guten Zweck zusammengekommen !!!<\/p>\n<p>Am Donnerstag, den 13.02.2014, wird Michael Wendler pers&ouml;nlich den Betrag der &quot;Dinslakener Tafel&quot; &uuml;bergeben.<\/p>\n<p>Facebook-Seite von Michael Wendler (Textvorlage)<br \/>http:\/\/www.ariola.de<br \/>http:\/\/www.michael-wendler.de<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die &#8222;Dinslakener Tafel&#8220; darf sich \u00fcber einen stattlichen Betrag freuen&#8230;:\u00a0 Die Charity-Auktion von MICHAEL WENDLER f&uuml;r die &quot;Dinslakener Tafel&quot; ist<\/p>\n","protected":false},"author":2,"featured_media":106397,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[28],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/106396"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=106396"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/106396\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/106397"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=106396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=106396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=106396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}