{"id":106363,"date":"2014-02-13T00:00:00","date_gmt":"2014-02-13T00:00:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=106363"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"FLORIAN-SILBEREISEN-Am-2203201-106362","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/volksmusik\/FLORIAN-SILBEREISEN-Am-2203201-106362\/","title":{"rendered":"FLORIAN SILBEREISEN <br \/> Am 22.03.2014 steigt &quot;Das gro\u00dfe Fest zum Jubil\u00e4um&quot;!"},"content":{"rendered":"<p>&#8222;Die \u00fcberraschende Show mit Florian Silbereisen&#8220; wird diesmal aus der GETEC Arena Magdeburg \u00fcbertragen!\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">Am 22. M&auml;rz 2014 wird aus dem &quot;Fr&uuml;hlingsfest der 100.000 Bl&uuml;ten&quot;, wie die Sendung im vergangenen Jahr hie&szlig;, &quot;Das gro&szlig;e Fest zum Jubil&auml;um&quot; &#8211; &quot;Die &uuml;berraschende Show mit Florian Silbereisen&quot;. Der Grund: FLORIAN SILBEREISEN feiert sein 10-j&auml;hriges Jubil&auml;um als Pr&auml;sentator der &quot;Feste&quot;. Die Show-Reihe selbst gibt es seit zwanzig Jahren.<\/p>\n<p>Bis auf Newcomerin <em>Oonagh<\/em>, die gerade einen Top 10-Einstieg in den letzten Album-Charts hingelegt hat, werden alle Namen noch strengstens unter Verschluss gehalten.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>&quot;Die FESTE&quot;<\/strong> (Quelle: MDR)<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Seit zwanzig Jahren sind Die FESTE die gro&szlig;en Unterhaltungsshows am Samstagabend mit hochkar&auml;tigen G&auml;sten, vielen au&szlig;ergew&ouml;hnlichen Ideen, spektakul&auml;ren Aktionen und Musik von Volksmusik &uuml;ber Schlager bis hin zu Musical und Operette. Seit Februar 2004 pr&auml;sentiert Showmaster Florian Silbereisen die erfolgreichste Musikshowreihe im deutschen Fernsehen, die immer wieder ein Millionenpublikum begeistert. Seine Sendungen sind die gro&szlig;en Shows der &Uuml;berraschungen, in denen nicht nur die auftretenden K&uuml;nstler in ungew&ouml;hnliche Rollen schl&uuml;pfen, sondern vor allem auch Florian Silbereisen sein vielseitiges Talent als Entertainer unter Beweis stellt &ndash; als S&auml;nger, Musiker, T&auml;nzer, Schauspieler, Artist oder Akrobat.<\/p>\n<p><em>Foto-Credit: MDR \/ Andreas Lander<\/em><\/p>\n<p>Andy Tichler, Chefredakteur www.smago.de<\/p>\n<p>http:\/\/www.mdr.de\/feste-der-volksmusik\/index.html<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8222;Die \u00fcberraschende Show mit Florian Silbereisen&#8220; wird diesmal aus der GETEC Arena Magdeburg \u00fcbertragen!\u00a0 Am 22. M&auml;rz 2014 wird aus<\/p>\n","protected":false},"author":2,"featured_media":106364,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[30],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/106363"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=106363"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/106363\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/106364"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=106363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=106363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=106363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}