{"id":105601,"date":"2014-03-03T13:55:00","date_gmt":"2014-03-03T13:55:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=105601"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"UDO-JUERGENS-Album-Praesentati-105600","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/schlager\/UDO-JUERGENS-Album-Praesentati-105600\/","title":{"rendered":"UDO J\u00dcRGENS <br \/> Album-Pr\u00e4sentation &quot;Mitten im Leben&quot; und Gold-Verleihung in Wien!"},"content":{"rendered":"<p>Dietmar Lienbacher von Sony Music Austria: &#8222;Udo J\u00fcrgens ist der gr\u00f6\u00dfte deutschsprachige Entertainer und K\u00fcnstler unserer Zeit!&#8220;!\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">UDO J&Uuml;RGENS pr&auml;sentierte am 28.02.2014 im frisch renovierten Wiener Szeneclub &bdquo;Box&nbsp; &#8211; Vienna&ldquo; sein neuestes Studioalbum &bdquo;Mitten im Leben&ldquo;.<\/p>\n<p>Im ehemaligen Club von Jazzlegende Joe Zawinul (&dagger; 2007), mit den Udo J&uuml;rgens seit seiner Jugend befreundet war und auch des &Ouml;fteren gemeinsam jamte, erz&auml;hlte Udo J&uuml;rgens auch von einer seiner ersten Begegnung und davon, dass Joe Zawinul damals zu ihm sagte <em>&bdquo;Klavierspielen kannst net Bursche, aber wennst singst ist des tadellos&ldquo;.<\/em><\/p>\n<p>Zahlreiche Medienvertretern aus dem Bereich TV, Radio, Print und Online lauschten aufmerksam als Udo J&uuml;rgens einige seiner Lieder aus dem gro&szlig;artig produzierten neuen Album &bdquo;Mitten im Leben&ldquo; am Klavier zum Besten gab. Nachdem Barbara St&ouml;ckl grandios durch den Nachmittag f&uuml;hrte &uuml;berreichten anschlie&szlig;end auf der B&uuml;hne Dietmar Lienbacher (Division Head Sony Music Austria) und Peter Schilling (Director Ariola) den Goldaward f&uuml;r das letzte Studioalbum &bdquo;Der ganz normale Wahnsinn&ldquo;&nbsp; an den gro&szlig;artigen Entertainer Udo J&uuml;rgens, seinem Manager Freddy Burger, Mucki Stammler (FB Management) und an den Produzenten Peter Wagner.<\/p>\n<p>Nach einem perfekt gelungenen Nachmittag mit Udo J&uuml;rgens meinte Dietmar Lienbacher: &bdquo;Udo J&uuml;rgens &uuml;bt eine Faszination aus, der man sich kaum entziehen kann. Er ist der gr&ouml;&szlig;te deutschsprachige Entertainer und K&uuml;nstler unserer Zeit. Wir sind sehr stolz mit Ihm arbeiten zu d&uuml;rfen.&ldquo;<\/p>\n<p>Das neue Studioalbum von Udo J&uuml;rgens &bdquo;Mitten im Leben&ldquo; wurde am 21.02.2014 ver&ouml;ffentlicht und ab Dezember 2014 ist Udo J&uuml;rgens mit der gleichnamigen Konzerttournee 3x in &Ouml;sterreich zu sehen &ndash; 02.12. Salzburg, 03.12. Graz und 05.12. Wien.<\/p>\n<p style=\"text-align: justify;\">\n&nbsp;<\/p>\n<p style=\"text-align: justify;\"><em>Foto-Credit: Alexander Tuma<\/em><\/p>\n<p>Sony Music Austria (Textvorlage)<br \/>http:\/\/www.sonymusic.at\/<br \/>http:\/\/www.udojuergens.de<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dietmar Lienbacher von Sony Music Austria: &#8222;Udo J\u00fcrgens ist der gr\u00f6\u00dfte deutschsprachige Entertainer und K\u00fcnstler unserer Zeit!&#8220;!\u00a0 UDO J&Uuml;RGENS pr&auml;sentierte<\/p>\n","protected":false},"author":2,"featured_media":105602,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[29],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/105601"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=105601"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/105601\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/105602"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=105601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=105601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=105601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}