{"id":105343,"date":"2014-03-10T00:00:00","date_gmt":"2014-03-10T00:00:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=105343"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"ANDY-BORG-Andy-der-Bruchpilot-105342","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/schlager\/ANDY-BORG-Andy-der-Bruchpilot-105342\/","title":{"rendered":"ANDY BORG <br \/> Andy, der Bruchpilot: Schlechteste &quot;Musikantenstadl&quot; Quote aller Zeiten &#8211; leider!"},"content":{"rendered":"<p>Die Sendung aus der Arena Nova in Wiener Neustadt (Motto diesmal: &#8222;Fliegen&#8220;) kam n\u00e4mlich ausgesprochen pfiffig daher (, auch wenn sie &#8211; von den Quoten her &#8211; eher eine Bruchlandung war)&#8230;:\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">Man kann vermutlich froh sein, dass die Entscheidung, dass der &quot;Musikantenstadl&quot; mindestens bis Ende 2015 weiterlaufen wird (auch wenn im n&auml;chsten Jahr eine Live-Sendung gestrichen wird), vor dem 9. M&auml;rz 2014 gefallen ist. Denn die Quote-Ausbeute der ersten &quot;Musikantenstadl&quot; Sendung 2014 live aus Wiener Neustadt vom 08.03.2014, ist leider nicht sonderlich berauschend.<\/p>\n<p>Mit 3,85 Millionen Zuschauern und 12,7 % Marktanteil wurde sogar das schlechteste Ergebnis f&uuml;r eine regul&auml;re &quot;Musikantenstadl&quot; Sendung gemessen. Lediglich die &quot;Best Of&quot; Folge im August 2012 lag mit 3,67 Millionen Zuschauern noch weiter darunter.<\/p>\n<p>Ganz schlecht sah es in der Zielgruppe der 14- bis 49-J&auml;hrigen aus: 0,31 Millionen Zuschauer und &quot;vernichtende&quot; 2,9 % Marktanteil (Zitat Quotenmeter) sind leider alles andere als &uuml;berzeugend. Selbst in der &quot;erweiterten Zielgruppe der 14- bis 59-J&auml;hrigen&quot; wurden nur 0,65 Millionen Zuschauer und 4,0 % Marktanteil gemessen.<\/p>\n<p>Wenn man sieht, wie viel junges Publikum in den Arenen, in denen der &quot;Musikantenstadl&quot; live ausgerichtet wird, zugegen ist, versteht man die Welt nicht mehr.&nbsp;<\/p>\n<p>Das leider wirklich &auml;u&szlig;erst unbefriedigende Ergebnis schmerzt umso mehr, als dass der unter dem Motto &quot;Fliegen&quot; stehende erste &quot;Musikantenstadl&quot; in diesem Jahr ausgesprochen pfiffig daherkam, was nicht zuletzt an dem bestens aufgelegten Gastgeber ANDY BIRG lag, der am Samstagabend einen ganz hervorragenden Job gemacht hat.<\/p>\n<p>Andy Tichler, Chefredakteur www.smago.de<br \/>http:\/\/www.musikantenstadl.tv<br \/>http:\/\/www.andy-borg.de\/Startseite.2.0.html<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Sendung aus der Arena Nova in Wiener Neustadt (Motto diesmal: &#8222;Fliegen&#8220;) kam n\u00e4mlich ausgesprochen pfiffig daher (, auch wenn<\/p>\n","protected":false},"author":2,"featured_media":105344,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[29],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/105343"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=105343"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/105343\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/105344"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=105343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=105343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=105343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}