{"id":105148,"date":"2014-03-15T00:00:00","date_gmt":"2014-03-15T00:00:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=105148"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"LINDA-FELLER-Sommer-Die-aktu-105147","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/country\/LINDA-FELLER-Sommer-Die-aktu-105147\/","title":{"rendered":"LINDA FELLER <br \/> &quot;Sommer&quot; &#8211; Die aktuelle Single aus dem neuen Album &quot;Und immer noch ich&quot;!"},"content":{"rendered":"<p>Linda Feller ist neu bei Monopol Records unter Vertrag! Die Single erscheint am 28.03.2014, das Album folgt am 2. Mai!\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">Mit neuer Single, neuem Album und nat&uuml;rlich wieder voll musikalischer Power und Lebensfreude startet die geb&uuml;rtige Th&uuml;ringerin LINDA FELLER in ihr 30. Jubil&auml;umsjahr. Sie gilt als die erfolgreichste Deutsche Country-Lady und gibt mit ihrer Singleauskopplung &bdquo;Sommer&ldquo; einen ersten Vorgeschmack auf das im Mai erscheinende Album &bdquo;Und immer noch ich&ldquo;.<\/p>\n<p>Frech, sexy, poppig, aber auch gef&uuml;hlvoll, gepaart mit Stilelementen der Countrymusik &#8211; so pr&auml;sentiert sich die K&uuml;nstlerin Linda Feller eindrucksvoll von einer ganz neuen Seite.<\/p>\n<p>Linda Feller bedient keine Klischees &ndash; sie ist eine Powerfrau und geht stets ihren eigenen Weg.<\/p>\n<p>Neu im Team ist der Produzent und Autor Ralf &bdquo;Ralle&ldquo; Rudnik (Ex-H&ouml;hner). F&uuml;r ihn und die S&auml;ngerin Linda Feller geht mit der Zusammenarbeit jetzt endlich ein gro&szlig;er Traum in Erf&uuml;llung, denn beide kennen und sch&auml;tzen sich seit Jahren.<\/p>\n<p>Auf ihrer neuen CD erz&auml;hlt Linda Feller Geschichten, die das Leben schreibt. Mal wecken sie Erinnerungen, mal erz&auml;hlen sie von den kleinen Schw&auml;chen, mal machen sie nachdenklich, mal zaubern sie ein L&auml;cheln auf das Gesicht.<\/p>\n<p>&bdquo;Spa&szlig; am Leben und an der Liebe lassen jeden Tag zu einem Besonderen werden.&ldquo;<\/p>\n<p>Diese ganz eigene Sichtweise auf das Leben m&ouml;chte die zierliche Powerfrau auch ihrem Publikum vermitteln&hellip;<\/p>\n<p>Monopol Records (Textvorlage)<br \/>http:\/\/www.meiselmusic.de\/<br \/>http:\/\/www.linda-feller.de\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Linda Feller ist neu bei Monopol Records unter Vertrag! Die Single erscheint am 28.03.2014, das Album folgt am 2. Mai!\u00a0<\/p>\n","protected":false},"author":2,"featured_media":105149,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[4],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/105148"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=105148"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/105148\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/105149"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=105148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=105148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=105148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}