{"id":104530,"date":"2014-03-31T00:00:00","date_gmt":"2014-03-31T00:00:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=104530"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"ANDREA-BERG-Titel-Der-letzte-T-104529","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/schlager\/ANDREA-BERG-Titel-Der-letzte-T-104529\/","title":{"rendered":"ANDREA BERG <br \/> Titel &quot;Der letzte Tag im Paradies&quot; seit 28.03.2014 als Download-Single erh\u00e4ltlich!"},"content":{"rendered":"<p>Der Song ist auch in einem speziellen &#8222;DJ Mix&#8220; verf\u00fcgbar!\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">Heimlich, still und leise wurde am Freitag (28.03.2014) der Titel &quot;Der letzte Tag im Paradies&quot; von ANDREA BERG als Download-Single ver&ouml;ffentlicht. Gl&uuml;cklicherweise jedoch hat uns ein aufmerksamer <em>smago!<\/em> Leser auf diese Download-Ver&ouml;ffentlichung hingewiesen. Denn: Es wurde eigens auch ein spezieller &quot;DJ Mix&quot; produziert, der <strong><a href=\"http:\/\/www.amazon.de\/letzte-Tag-Paradies-DJ-Mix\/dp\/B00J4V69AG\/ref=sr_1_2?ie=UTF8&amp;qid=1396216610&amp;sr=8-2&amp;keywords=der+letzte+tag+im+paradies+andrea+berg\">HIER<\/a><\/strong> verf&uuml;gbar ist.<\/p>\n<p><strong>Die Single-CD &quot;Der letzte Tag im Paradies&quot;<\/strong> (Quelle: Ariola)<\/p>\n<p>Es ist kaum verwunderlich, dass Andrea Bergs aktuelles Album &bdquo;Atlantis&ldquo; zu den erfolgreichsten ihrer einzigartigen und erfolgreichen Karriere geh&ouml;rt. Denn die Platte ist nur so gespickt mit absoluten Top-Titeln. Und der n&auml;chste steht bereits in den Startl&ouml;chern: Mit &bdquo;Der letzte Tag im Paradies&ldquo; verspricht auch die dritte Single-Auskopplung ein absoluter Hit zu werden.<\/p>\n<p>Die geb&uuml;rtige Krefelderin pr&auml;sentiert diesen Titel derzeit auch bei ihren spektakul&auml;ren Auftritten der k&uuml;rzlich gestarteten Atlantis-Tour. Die Fans sind begeistert, die Medien voll des Lobes. Kein Wunder bei einem solchen Star, der mit jeder Ver&ouml;ffentlichung f&uuml;r mindestens einen Rekord sorgt. &bdquo;Atlantis&ldquo; ist das aktuelle, mittlerweile siebte Nummer-1-Album in Folge. Mitte Dezember erreichten die Verkaufszahlen bereits die dreifache Goldmarke. Der weitere Trend? Nach oben &ndash; denn jetzt steht der Tontr&auml;ger bei Doppel-Platin.<\/p>\n<p>&bdquo;Wei&szlig;t Du, wie sich das anf&uuml;hlt, aus dem Himmel zu fliegen&ldquo;? fragt Andrea Berg in der neuen Single, in der sich alles um entt&auml;uschte Liebe und um Betrug dreht. Ein f&uuml;r viele unangenehmes Thema, das aber leider allt&auml;glich vorkommt. Die 48-J&auml;hrige nimmt sich die Gef&uuml;hle der Menschen zu Herzen. Die aktuelle, aufw&auml;ndige, atemberaubende Show auf der ausverkauften Tour zeigt das sehr deutlich: Die Halle &ndash; sprich: die Tausenden von Fans singen mit, wortw&ouml;rtlich, auch wenn der Text ihre pers&ouml;nlichen Erfahrungen nur allzu deutlich anspricht. Oder eben genau deshalb. Gemeinsam singen, mit Andrea Berg, und dann dar&uuml;ber erleichtert schmunzeln. Ein unvergesslicher Moment. &Uuml;brigens l&auml;uft die bereits ausverkaufte &bdquo;Atlantis&ldquo;- Tour noch bis Ende M&auml;rz und macht quer durch Europa Station: Deutschlands erfolgreichste S&auml;ngerin wird nicht nur im deutschsprachigen Raum begeistern; sie steht ebenso in Frankreich, Belgien und D&auml;nemark auf der B&uuml;hne! Fans, die bereits Karten f&uuml;r die laufende Tournee besitzen, d&uuml;rfen sich also schon jetzt auf einen atemberaubenden Tag freuen, der sicherlich nicht der letzte im Paradies sein wird.<\/p>\n<p>\n<em>Foto-Credit: Lado Alexi<\/em><\/p>\n<p>Andy Tichler, Chefredakteur www.smago.de<br \/>http:\/\/www.ariola.de<br \/>http:\/\/www.andrea-berg.de<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Song ist auch in einem speziellen &#8222;DJ Mix&#8220; verf\u00fcgbar!\u00a0 Heimlich, still und leise wurde am Freitag (28.03.2014) der Titel<\/p>\n","protected":false},"author":2,"featured_media":104531,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[29],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/104530"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=104530"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/104530\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/104531"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=104530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=104530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=104530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}