{"id":104422,"date":"2014-04-04T00:00:00","date_gmt":"2014-04-04T00:00:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=104422"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"JONNY-HILL-Wissenswertes-ueber-104421","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/country\/JONNY-HILL-Wissenswertes-ueber-104421\/","title":{"rendered":"JONNY HILL <br \/> Wissenswertes \u00fcber seine neue CD &quot;Bitte treten Sie zur\u00fcck&quot;!"},"content":{"rendered":"<p>Wer bei dem Titelsong keine Tr\u00e4ne(n) vergie\u00dft, der hat ein Herz aus Stein&#8230;!\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\"><strong><em>&bdquo;Bitte treten Sie zur&uuml;ck&ldquo;<\/em><\/strong><em> ist das neue Album des &ouml;sterreichischen S&auml;ngers Jonny Hill. Es bringt einmal mehr die besten Seiten des gefeierten Interpreten zur Geltung: Seine musikalische Vielfalt, seine tiefen, eingehenden Texte. Und nat&uuml;rlich diese wunderbare, poetische Stimme. Seit &uuml;ber vier Jahrzehnten im Gesch&auml;ft, klingt Jonny Hill moderner, anspruchsvoller, h&ouml;renswerter denn je.<\/em><\/p>\n<p>Jonny Hill macht deutschsprachige Countrymusik. Er geh&ouml;rt zu jenen K&uuml;nstlern oder Bands, die diese Stilrichtung in Deutschland, der Schweiz und seinem Heimatland &Ouml;sterreich &quot;salonf&auml;hig&quot; gemacht haben. Oder sollte es besser hei&szlig;en: <em>saloonf&auml;hig<\/em>? Wohl doch nicht, denn die Songs Jonny Hills sind alles andere als Cowboymusik. Und das, obwohl so typische Instrumente wie die Dobro-Country-Gitarre, Mundharmonika oder die Pedalsteel zu h&ouml;ren sind. &quot;Ich singe nicht von der Pr&auml;rie&quot;, sagt Jonny Hill, &quot;ich trage auch keinen Stetson oder ein Fransenhemd. Country, das ist ist eher die Farbe meiner Musik.&quot;<\/p>\n<p>Das wird auch wieder bei dem neuen Album <strong>&quot;Bitte treten Sie zur&uuml;ck&quot;<\/strong> deutlich. Keine Pferde, keine Colts, kein Saloon. Daf&uuml;r Geschichten aus dem Alltag, die so jedem von uns passieren k&ouml;nnen. Da ist allen voran das Titel-Lied &quot;Bitte treten Sie zur&uuml;ck&quot;, das von einer Frau handelt, deren Mann die t&auml;glich einfahrenden Z&uuml;ge angesagt hatte. Nun ist er gestorben, doch seine Frau geht noch immer jeden Tag auf den Bahnhof, nur um die Stimme ihres Mannes zu h&ouml;ren. &quot;Ich habe diese Geschichte tats&auml;chlich mal in der Zeitung gelesen&quot;, so Jonny Hill, &quot;sie hat mich tief bewegt. Daraus ist der Song entstanden.&quot;<\/p>\n<p>Ganz anders das Lied &bdquo;Kaffee ohne Zucker&ldquo;. Ganz anders und doch &auml;hnlich. Denn auch hier geht es wieder um eine allt&auml;gliche Situation. Ein Mann wohnt unter einer begehrenswerten Frau &ndash; nur traut er sich nicht recht an sie heran. Lange &uuml;berlegt er, wie er ihr n&auml;her kommen k&ouml;nnte. Bis sie selbst eines Tages bei ihm klingelt und um Zucker bittet. Ob ihre s&uuml;&szlig;e Idee klappt?<\/p>\n<p>Vielleicht werden die beiden ja ein Paar, vielleicht werden sie eines Tages sogar Goldene Hochzeit feiern. Eben diesem heutzutage selten gewordenen Ereignis ist das Lied &bdquo;Ist die sch&ouml;nste Zeit vor&uuml;ber&ldquo; gewidmet. Oder besser gesagt: Es ist Jonny Hills Frau gewidmet, mit der der S&auml;nger seit kurzem 50 Jahre verheiratet ist. &bdquo;Ist die sch&ouml;nste Zeit vor&uuml;ber\/ist der Sommer schon vorbei\/oder kommt er nochmals wieder\/ unser wunderbarer Mai?&ldquo; Es ist ein vertontes Liebesgedicht, das vordergr&uuml;ndig melancholische Saiten anschl&auml;gt &#8211; schlie&szlig;lich besingt es auch die Endlichkeit unseres Daseins. Doch was es tats&auml;chlich feiert, das ist die Kraft einer Liebe, die jede Zeit &uuml;berdauert.<\/p>\n<p>&bdquo;Ich mache keine Stimmung, ich will mit meinen Liedern vor allem ber&uuml;hren&ldquo;, sagt Jonny Hill. Dabei ist der S&auml;nger nie wehleidig, zielt seine die Interpretation niemals auf blo&szlig;e R&uuml;hrseligkeit ab. &bdquo;Das &#39;Bacherl&ldquo; &uuml;ber das ein &#39;Br&uuml;ckerl geht, ist zwar auch sch&ouml;n&ldquo;, sagt Jonny Hill. &bdquo;Aber es gibt nicht nur die heile Welt.&ldquo; Doch bei allen Problemen, vor der sich auch Jonny Hill nicht verschlie&szlig;t &ndash; am Ende muss es stets einen positiven Ausklang geben. &bdquo;Nicht unbedingt ein Happyend, aber doch wenigstens ein Licht am Horizont, so Jonny Hill.<\/p>\n<p>Beinahe w&ouml;rtlich ist dieses Licht im Lied &quot;Mama und ich&quot; zu nehmen. Hier geht es um seine Kinder, seine Enkel. &quot;Ihr seid meine Kinder, mein Geschenk an die Welt, mein helles Licht&quot;. Fast klingt es wie das Verm&auml;chtnis eines lebenserfahrenen Mannes&nbsp; an die j&uuml;ngere Generation. Eines Mannes, der wei&szlig;, dass er zwar Ratschl&auml;ge geben kann. &bdquo;Doch gehen m&uuml;ssen sie die Wege selbst&ldquo;, sagt Jonny Hill. Oder, wie es im Lied sehr viel lyrischer, sehr viel eing&auml;nglicher hei&szlig;t: &bdquo;Wollt ihr wissen wie man tanzt, dann schaut auf Mama und mich&quot;. &bdquo;Mama und ich&ldquo; geh&ouml;rt zweifelsfrei zu den sch&ouml;nsten, bewegendsten Liedern auf dem Album.<\/p>\n<p>Fast alle Texte des Albums <strong>&bdquo;Bitte treten Sie zur&uuml;ck&ldquo;<\/strong> hat Jonny Hill selbst geschrieben. Die Musik &ndash; mal rockig, mal sanft, mal beschwingt, dann wieder getragen &ndash; stammt ebenfalls von Jonny Hill in Zusammenarbeit mit Sigmar Strecker, Manu Stix, Halef Krug und Werner Becker. Produziert wurde es im &bdquo;ambient studio&ldquo; in Tirol. &bdquo;Ich muss nicht nach Nashville, um Countrymusik zu machen&ldquo;, so Jonny Hill. &bdquo;Mir ist wichtig, dass Musiker die Texte verstehen, dann geht auch ihre Musik viel tiefer.&ldquo; Die Songs wurden life eingespielt mit Gitarre, Geige, Drums, Piano &#8211; gute alte handgemachte T&ouml;ne, also. Nach 40 Jahren im Gesch&auml;ft und &uuml;ber 400 Songs ist Jonny Hill so frisch, modern und kreativ wie wenige Newcomer des Gesch&auml;fts.<\/p>\n<p>&bdquo;Ist die sch&ouml;nste Zeit vor&uuml;ber&ldquo;? Mit dem neuen Album <strong>&bdquo;Bitte treten Sie zur&uuml;ck&ldquo;<\/strong>&nbsp; von Jonny Hill ist die Antwort klar: Die sch&ouml;nste Zeit ist jetzt. Sie hat gerade begonnen.<\/p>\n<p>MCP Sound &#038; Media (Textvorlage)<br \/>http:\/\/www.mcpsound.at<br \/>http:\/\/www.jonny-hill.info\/das-gala-konzert.html<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wer bei dem Titelsong keine Tr\u00e4ne(n) vergie\u00dft, der hat ein Herz aus Stein&#8230;!\u00a0 &bdquo;Bitte treten Sie zur&uuml;ck&ldquo; ist das neue<\/p>\n","protected":false},"author":2,"featured_media":104423,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[4],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/104422"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=104422"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/104422\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/104423"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=104422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=104422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=104422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}