{"id":103183,"date":"2014-05-11T00:00:00","date_gmt":"2014-05-11T00:00:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=103183"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"STEFANIE-HERTEL-Heute-09052014-103182","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/volksmusik\/STEFANIE-HERTEL-Heute-09052014-103182\/","title":{"rendered":"STEFANIE HERTEL <br \/> Heute (09.05.2014) in der &#39;Freak-Show&#39; &quot;Zimmer frei!&quot; zu Gast!"},"content":{"rendered":"<p>&#8222;Mit \u00b4ABBA\u00b4 im Herzen einen Jodel-Crashkurs geben&#8220; \/\/ WDR Fernsehen, 22:15 Uhr &#8211; 23:15 Uhr!\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">Sie ist ein Superstar der Volksmusik und feierte im vergangenen Jahr ihr 30. B&uuml;hnenjubil&auml;um, obwohl sie gerade erst 34 Jahre alt ist: STEFANIE HERTEL. Aber nicht nur die Fans der volkst&uuml;mlichen Musik sch&auml;tzen die geb&uuml;rtige Vogtl&auml;nderin, in der Show &bdquo;Let&rsquo;s dance&ldquo; und als TV-Moderatorin zeigte Stefanie Hertel inzwischen noch ganz andere Talente.<\/p>\n<p>Ihren ersten Auftritt hatte sie bereits mit vier Jahren. &bdquo;Ich wollte unbedingt auf die B&uuml;hne&ldquo;, erz&auml;hlt Stefanie Hertel bei &bdquo;Zimmer frei!&ldquo;. Auf der Weihnachtstournee ihres Vaters, einem bekannten Volksmusik-S&auml;nger, bekam sie ihre Chance.<em> &bdquo;Der Papa stand neben mir und wollte mir eine moralische St&uuml;tze geben&ldquo;, lacht sie: &bdquo;Ich hab&rsquo; nur gedacht, was will er denn jetzt hier, das ist meine B&uuml;hne!&ldquo;<\/em><\/p>\n<p>Im damaligen DDR-Fernsehen pr&auml;sentierte sie ihr Gesangstalent erstmals 1985, als Sechsj&auml;hrige. F&uuml;nf Jahre sp&auml;ter, kurz nach der Wiedervereinigung, trat sie in der &bdquo;Volkst&uuml;mlichen Hitparade&ldquo; auf und setzte danach zu einem wahren Siegeszug in der Volksmusik-Szene an. Mehrfach wurde sie mit Preisen wie der &bdquo;Goldenen Stimmgabel&ldquo; und der &bdquo;Goldenen Henne&ldquo; ausgezeichnet, sechsmal gewann sie die &bdquo;Krone der Volksmusik&ldquo;.<\/p>\n<p>Am Sonntag &uuml;berraschen Christine Westermann und G&ouml;tz Alsmann den eingeschworenen &bdquo;Abba&ldquo;-Fan zu ihrer Freude mit einer spektakul&auml;ren Aktion: Beim &bdquo;Gro&szlig;en Abba-Fest der Volksmusik&ldquo; mischt auch &bdquo;H&ouml;hner&ldquo;-Frontmann Henning Krautmacher mit. Stefanie Hertel revanchiert sich mit einem Jodel-Crashkurs f&uuml;r das Studiopublikum und zeigt ihr Jazz-Feeling bei dem Song-Klassiker &bdquo;Fly me to the Moon&ldquo;. Ein prominenter Kollege kommt nat&uuml;rlich auch zu Wort: Andy Borg. Er hat Stefanie Hertel kennengelernt, als sie noch ein Kinderstar war.&nbsp;&nbsp;&nbsp;<\/p>\n<p><em>Foto-Credit: WDR \/ Ben Knabe<\/em><\/p>\n<p>WDR (Textvorlage)<br \/>http:\/\/www.wdr.de<br \/>http:\/\/www1.wdr.de\/fernsehen\/unterhaltung\/zimmerfrei\/index.html<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8222;Mit \u00b4ABBA\u00b4 im Herzen einen Jodel-Crashkurs geben&#8220; \/\/ WDR Fernsehen, 22:15 Uhr &#8211; 23:15 Uhr!\u00a0 Sie ist ein Superstar der<\/p>\n","protected":false},"author":2,"featured_media":103184,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[30],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/103183"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=103183"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/103183\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/103184"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=103183"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=103183"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=103183"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}