{"id":101236,"date":"2014-07-04T00:00:00","date_gmt":"2014-07-04T00:00:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=101236"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"SEBASTIAN-CHARELLE-Michael-Som-101235","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/pop-schlager\/SEBASTIAN-CHARELLE-Michael-Som-101235\/","title":{"rendered":"SEBASTIAN CHARELLE <br \/> Michael Sommer informiert&#8230;: &quot;Charello&quot; macht Baby-Pause!"},"content":{"rendered":"<p>\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">&quot;Sebastian Charelle macht eine &#39;Baby&#39;-Pause von der B&uuml;hne&quot;, so informiert Michael Sommer, Manager und Freund von SEBASTIAN CHARELLE, die &Ouml;ffentlichkeit. Der sympathische S&auml;nger aus Niedersachsen freut sichmit seiner Frau auf die Geburt ihres ersten Kindes.<\/p>\n<p>F&uuml;r Sebastian ist es ganz wichtig in dieser Phase ganz nah bei seiner Familie zu sein. Wer Sebastian kennt, wei&szlig;&nbsp; genau, wie bedeutend ihm diese Momente im leben sind.<\/p>\n<p>Zum Jahresende wird sich Sebastian Charelle dann auf der B&uuml;hne zur&uuml;ckmelden.<\/p>\n<p>Bis dahin wird Sebastian weiter mit seinem Team an einem neuen Album, welches f&uuml;r 2015 geplant ist, arbeiten<\/p>\n<p>Sommer Concerts &#038; Marketing UG , Saskia Sommer (Textvorlage)<br \/>http:\/\/www.toughmusic.de\/<br \/>http:\/\/www.veranstaltungsservice-sommer.de\/kuenstlermanagement\/sebastian-charelle.html<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 &quot;Sebastian Charelle macht eine &#39;Baby&#39;-Pause von der B&uuml;hne&quot;, so informiert Michael Sommer, Manager und Freund von SEBASTIAN CHARELLE, die<\/p>\n","protected":false},"author":2,"featured_media":101237,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[28],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/101236"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=101236"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/101236\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/101237"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=101236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=101236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=101236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}