{"id":100381,"date":"2014-07-25T00:00:00","date_gmt":"2014-07-25T00:00:00","guid":{"rendered":"https:\/\/smago.de\/ws\/?p=100381"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"TOM-ASTOR-Du-willst-mich-nicht-100380","status":"publish","type":"post","link":"https:\/\/smago.de\/ws2\/country\/TOM-ASTOR-Du-willst-mich-nicht-100380\/","title":{"rendered":"TOM ASTOR <br \/> &quot;Du willst mich nicht verbiegen&quot; &#8211; Die zweite Radio-Single aus seinem Chart-Album &quot;Volle Kraft voraus&quot;!"},"content":{"rendered":"<p>Ein Lied voller positiver Kraft, das die H\u00f6rer zweifellos mitrei\u00dft!\u00a0 <!-more-><\/p>\n<p style=\"text-align: justify;\">Eines steht fest: Wenn man bereits 50 Jahre auf der B&uuml;hne zuhause ist, hat man vieles gesehen und durchlebt. Man ist einen gro&szlig;en Teil seines Weges gegangen und wei&szlig; einfach, worauf es im Leben ankommt. So ist TOM ASTOR durchaus der sprichw&ouml;rtliche &bdquo;Fels in der Brandung&ldquo; geblieben, wo viele andere K&uuml;nstler sich den Str&ouml;mungen der Musikbranche hingegeben h&auml;tten &ndash; und das ist es, worauf Musikfans vertrauen k&ouml;nnen. Wo Tom Astor drauf steht, ist auch Tom Astor drin. Und was <em>IST<\/em> drin, im Repertoire des Ausnahmes&auml;ngers aus dem Sauerland? Nicht weniger als der authentische Sound Nordamerikas &ndash; nach Deutschland gebracht und vor allem mit Charakter und Ehrlichkeit dargeboten.<\/p>\n<p>Tom Astor der mit vielen Weltstars wie Willie Nelson, Kenny Rogers, Kris Kristofferson, John Denver und Johnny Cash Duette aufnahm. Selbstverst&auml;ndlich hat man da hohe Anspr&uuml;che &ndash; und denen ist Tom Astor auch auf &bdquo;Volle Kraft voraus!&ldquo;, seinem ersten Studioalbum seit 2010, treu geblieben.<\/p>\n<p>Die nun brandneu erscheinende Single &bdquo;Du willst mich nicht verbiegen&ldquo; ist in jeder Hinsicht ein typischer Tom Astor-Song geworden: Country pur vom Besten. &bdquo;In Country ist alles drin&ldquo;, sagt Tom Astor, &bdquo;Hillbilly, Bluegrass, Folk Rock &lsquo;n Roll und Blues.&ldquo; &ndash; und eben diese Vielseitigkeit des Country kostet Tom voll aus. Bereits bei den ersten T&ouml;nen des Schlagzeugs und der einsetzenden Gitarre wird man in die einzigartige Atmosph&auml;re des amerikanischen Country versetzt &ndash; und Toms kernige, warme Charakterstimme setzt dem Titel einen unnachahmlichen Stempel auf. Die Harmonien sitzen perfekt und erzeugen eine Art euphorische Gelassenheit, die sich schwer beschreiben l&auml;sst. Ein Lied voller positiver Kraft, das die H&ouml;rer zweifellos mitrei&szlig;t.<\/p>\n<p>TELAMO (Textvorlage)<br \/>http:\/\/www.telamo.de<br \/>http:\/\/www.tom-astor.de\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein Lied voller positiver Kraft, das die H\u00f6rer zweifellos mitrei\u00dft!\u00a0 Eines steht fest: Wenn man bereits 50 Jahre auf der<\/p>\n","protected":false},"author":2,"featured_media":100382,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":""},"categories":[4],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/100381"}],"collection":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/comments?post=100381"}],"version-history":[{"count":0,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/posts\/100381\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media\/100382"}],"wp:attachment":[{"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/media?parent=100381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/categories?post=100381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smago.de\/ws2\/wp-json\/wp\/v2\/tags?post=100381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}